{"id":27736,"date":"2025-03-17T19:21:47","date_gmt":"2025-03-17T13:51:47","guid":{"rendered":"https:\/\/www.verdantis.com\/?p=27736"},"modified":"2026-02-16T13:23:04","modified_gmt":"2026-02-16T07:53:04","slug":"articulo","status":"publish","type":"post","link":"https:\/\/www.verdantis.com\/es\/gestion-de-datos-maestros-2\/articulo\/","title":{"rendered":"Gesti\u00f3n de datos maestros de art\u00edculos"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"27736\" class=\"elementor elementor-27736\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7746d6b e-flex e-con-boxed e-con e-parent\" data-id=\"7746d6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6cd5ae1 elementor-widget elementor-widget-text-editor\" data-id=\"6cd5ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"0\" data-end=\"393\">Los datos maestros de art\u00edculos hacen referencia a un conjunto estructurado y estandarizado de atributos que definen los materiales, piezas de repuesto o productos utilizados en una organizaci\u00f3n. Act\u00faan como plantilla central o registro de referencia dentro de los sistemas ERP, EAM o de inventario, garantizando la coherencia y la precisi\u00f3n en los procesos de adquisici\u00f3n, fabricaci\u00f3n y mantenimiento.<\/p><p data-start=\"0\" data-end=\"393\">Se refiere al conjunto b\u00e1sico de informaci\u00f3n utilizada para identificar y describir elementos individuales -como materiales, productos, componentes o piezas de repuesto- dentro de un sistema empresarial como un sistema ERP (planificaci\u00f3n de recursos empresariales) o MRP (planificaci\u00f3n de necesidades de material).<\/p><p data-start=\"0\" data-end=\"393\">Organizaciones como SAP y Oracle han definido el maestro de art\u00edculos en diferentes t\u00e9rminos y bajo varios m\u00f3dulos. En Oracle, por ejemplo, se refieren al maestro de art\u00edculos en el m\u00f3dulo Oracle Inventory Management.<\/p><p data-start=\"0\" data-end=\"393\">En SAP, el equivalente se denomina <a href=\"https:\/\/www.verdantis.com\/materials-master-data-management\/\">Maestro de materiales<\/a>gestionados principalmente a trav\u00e9s del m\u00f3dulo de Gesti\u00f3n de Materiales (MM). A pesar de la diferencia terminol\u00f3gica, ambos cumplen la misma funci\u00f3n b\u00e1sica: garantizar la coherencia, precisi\u00f3n y centralizaci\u00f3n de los datos de materiales en las operaciones de aprovisionamiento, producci\u00f3n, mantenimiento y finanzas.<\/p><p data-start=\"0\" data-end=\"393\">Los datos maestros de art\u00edculos son un componente vital de varios sistemas empresariales, como la planificaci\u00f3n de recursos de material (MRP), la planificaci\u00f3n de recursos empresariales (ERP) y los sistemas de gesti\u00f3n de la informaci\u00f3n. <a href=\"https:\/\/www.verdantis.com\/mro-category-management\/\">Catalogaci\u00f3n MRO (Mantenimiento, Reparaci\u00f3n y Operaciones)<\/a> sistemas. Al proporcionar informaci\u00f3n precisa y actualizada, ayuda a las organizaciones a agilizar sus operaciones cotidianas, reducir errores y tomar decisiones con conocimiento de causa.<\/p><p data-start=\"395\" data-end=\"1042\" data-is-last-node=\"\" data-is-only-node=\"\">Una gesti\u00f3n adecuada de los datos maestros de art\u00edculos garantiza que las empresas puedan realizar un seguimiento de los materiales, optimizar el inventario, mejorar los procesos de aprovisionamiento y mantener la eficiencia operativa, apoyando en \u00faltima instancia flujos de trabajo m\u00e1s fluidos en departamentos como compras, fabricaci\u00f3n y mantenimiento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0be4b5 e-flex e-con-boxed e-con e-parent\" data-id=\"a0be4b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8417c2 elementor-widget elementor-widget-heading\" data-id=\"f8417c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"key-elements-of-item-master\">Elementos clave de Item Master<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a352e15 e-flex e-con-boxed e-con e-parent\" data-id=\"a352e15\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8d60772 e-grid e-con-full e-con e-child\" data-id=\"8d60772\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad0c947 elementor-widget elementor-widget-text-editor\" data-id=\"ad0c947\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"452\" data-end=\"499\"><p data-start=\"454\" data-end=\"499\">N\u00famero o c\u00f3digo del art\u00edculo (un identificador \u00fanico)<\/p><\/li><li data-start=\"500\" data-end=\"522\"><p data-start=\"502\" data-end=\"522\">Descripci\u00f3n del art\u00edculo<\/p><\/li><li data-start=\"523\" data-end=\"578\"><p data-start=\"525\" data-end=\"578\">Unidad de medida (por ejemplo, piezas, kilogramos, litros)<\/p><\/li><li data-start=\"579\" data-end=\"610\"><p data-start=\"581\" data-end=\"610\">Tipo o categor\u00eda de material<\/p><\/li><li data-start=\"611\" data-end=\"637\"><p data-start=\"613\" data-end=\"637\">Detalles del fabricante<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e80983 elementor-widget elementor-widget-text-editor\" data-id=\"7e80983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"638\" data-end=\"653\"><p data-start=\"640\" data-end=\"653\">Plazo de entrega<\/p><\/li><li data-start=\"654\" data-end=\"694\"><p data-start=\"656\" data-end=\"694\">Niveles de existencias y puntos de pedido<\/p><\/li><li data-start=\"695\" data-end=\"729\"><p data-start=\"697\" data-end=\"729\">Informaci\u00f3n sobre precios y costes<\/p><\/li><li data-start=\"730\" data-end=\"782\"><p data-start=\"732\" data-end=\"782\">C\u00f3digos de clasificaci\u00f3n (por ejemplo, UNSPSC, ECCN, HSN)<\/p><\/li><li data-start=\"783\" data-end=\"849\"><p data-start=\"785\" data-end=\"849\">Especificaciones t\u00e9cnicas (por ejemplo, dimensiones, peso, voltaje)<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8040d10 e-con-full form1 e-flex e-con e-child\" data-id=\"8040d10\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b0ba0f6 e-flex e-con-boxed e-con e-child\" data-id=\"b0ba0f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-02e880d e-con-full form1 e-flex e-con e-child\" data-id=\"02e880d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-061ec9b e-con-full form1 e-flex e-con e-child\" data-id=\"061ec9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-0bdc081 e-con-full e-flex e-con e-child\" data-id=\"0bdc081\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d52fb0 elementor-widget elementor-widget-heading\" data-id=\"8d52fb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Mantenga los datos de sus art\u00edculos precisos y organizados para obtener mejores resultados empresariales<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c695ce8 elementor-widget elementor-widget-heading\" data-id=\"c695ce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Prueba de concepto gratuita con sus propios datos de muestra<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6e03ff e-con-full e-flex e-con e-child\" data-id=\"b6e03ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34ddc48 elementor-widget elementor-widget-template\" data-id=\"34ddc48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"35768\" class=\"elementor elementor-35768\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10b489b1 e-con-full e-flex e-con e-child\" data-id=\"10b489b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-196cdd1d elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"196cdd1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"35768\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"196cdd1d\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"An In-depth Guide to Item Master Data Management\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"27736\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-lg  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-telephone elementor-field-group elementor-column elementor-field-group-Contact elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-Contact\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tN\u00ba de contacto\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input dir=\"ltr\" type=\"text\" name=\"change_name_Contact\" id=\"form-field-Contact\" class=\"elementor-field elementor-size-lg  elementor-field-telephone elementor-field-textual yee-ltr\" required=\"required\" data-auto=\"yes\" data-pre=\"\" data-excludecountries=\"\" data-onlyct=\"\" data-defcountry=\"\" data-hide_flag=\"\" data-hide_code=\"\" data-validation=\"yes\" data-name=\"Contact\" data-telephone_search=\"yes\" >\n\t\t<input onkeydown=\"return \/[0-9]|\\(|\\)|\\+|-|BACKSPACE\/i.test(event.key)\" type=\"hidden\" class=\"phone_check\" name=\"form_fields[Contact_check]\" value=\"\" >\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-Company elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-Company\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre de la empresa\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[Company]\" id=\"form-field-Company\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCorreo electr\u00f3nico profesional\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PROGRAMAR UNA REUNI\u00d3N<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11d386b6 elementor-widget elementor-widget-heading\" data-id=\"11d386b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Concierte una llamada de consulta no obligatoria con nuestro equipo de entrega para abordar los retos de la gesti\u00f3n de datos maestros<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-745375b e-flex e-con-boxed e-con e-parent\" data-id=\"745375b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c49004 elementor-widget elementor-widget-heading\" data-id=\"4c49004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"why-is-item-master-data-important\">\u00bfPor qu\u00e9 son importantes los datos maestros de art\u00edculos?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7064b20 e-con-full e-flex e-con e-parent\" data-id=\"7064b20\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57a6711 elementor-widget elementor-widget-heading\" data-id=\"57a6711\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"procurement-and-sourcing\">Adquisiciones y contrataci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c13a88 elementor-widget elementor-widget-text-editor\" data-id=\"3c13a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"280\" data-end=\"400\"><p data-start=\"282\" data-end=\"400\"><strong data-start=\"282\" data-end=\"307\">Descripciones precisas<\/strong> ayudar a los equipos de compras a identificar y abastecerse de los materiales o piezas correctos sin confusiones.<\/p><\/li><li data-start=\"401\" data-end=\"530\"><p data-start=\"403\" data-end=\"530\"><strong data-start=\"403\" data-end=\"440\">Nombres y atributos normalizados<\/strong> impedir que se creen art\u00edculos duplicados, lo que evita compras inconstantes o redundantes.<\/p><\/li><li data-start=\"531\" data-end=\"670\"><p data-start=\"533\" data-end=\"670\"><strong data-start=\"533\" data-end=\"568\">Enlaces a fabricantes y proveedores<\/strong> en los registros maestros de art\u00edculos garantizan que los pedidos vayan a proveedores autorizados, lo que reduce los riesgos y mejora el cumplimiento.<\/p><\/li><li data-start=\"671\" data-end=\"777\"><p data-start=\"673\" data-end=\"777\"><strong data-start=\"673\" data-end=\"689\">Precios<\/strong> en el maestro de art\u00edculos garantiza el c\u00e1lculo correcto de los costes y la presupuestaci\u00f3n de los pedidos de compra.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0409737 e-con-full e-flex e-con e-parent\" data-id=\"0409737\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-786aa4f elementor-widget elementor-widget-heading\" data-id=\"786aa4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"inventory-management\"> Gesti\u00f3n de existencias<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca49076 elementor-widget elementor-widget-text-editor\" data-id=\"ca49076\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"1163\" data-end=\"1310\"><p data-start=\"1165\" data-end=\"1310\"><strong data-start=\"1165\" data-end=\"1196\">Unidades de medida coherentes<\/strong> evitar el exceso o la falta de existencias debido a interpretaciones err\u00f3neas (por ejemplo, pedir 100 metros en lugar de 100 rollos).<\/p><\/li><li data-start=\"1311\" data-end=\"1411\"><p data-start=\"1313\" data-end=\"1411\"><strong data-start=\"1313\" data-end=\"1338\">Clasificaci\u00f3n adecuada<\/strong> permite un seguimiento preciso del uso de los art\u00edculos, los \u00edndices de rotaci\u00f3n y la criticidad.<\/p><\/li><li data-start=\"1412\" data-end=\"1540\"><p data-start=\"1414\" data-end=\"1540\"><strong data-start=\"1414\" data-end=\"1435\">Pol\u00edtica de existencias<\/strong> (como los niveles m\u00ednimo\/m\u00e1ximo y los puntos de pedido) almacenados en los registros de art\u00edculos impulsan los procesos automatizados de reposici\u00f3n.<\/p><\/li><li data-start=\"1541\" data-end=\"1675\"><p data-start=\"1543\" data-end=\"1675\"><strong data-start=\"1543\" data-end=\"1570\">Evitar duplicados<\/strong> significa que la misma pieza no se almacena en varias ubicaciones con distintos nombres, lo que inmoviliza el capital circulante.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9dcd3cf e-con-full e-flex e-con e-parent\" data-id=\"9dcd3cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a87b5fb elementor-widget elementor-widget-heading\" data-id=\"a87b5fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"supply-chain-planning\">Planificaci\u00f3n de la cadena de suministro<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-728d9ff elementor-widget elementor-widget-text-editor\" data-id=\"728d9ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"2048\" data-end=\"2179\"><p data-start=\"2050\" data-end=\"2179\"><strong data-start=\"2050\" data-end=\"2070\">Previsiones de la demanda<\/strong> y la planificaci\u00f3n de materiales se basan en la utilizaci\u00f3n hist\u00f3rica de los art\u00edculos. Si existen registros duplicados, la previsi\u00f3n est\u00e1 sesgada.<\/p><\/li><li data-start=\"2180\" data-end=\"2306\"><p data-start=\"2182\" data-end=\"2306\"><strong data-start=\"2182\" data-end=\"2200\">Datos sobre plazos<\/strong> (almacenado en el maestro de art\u00edculos) es esencial para planificar las entregas entrantes y mantener el flujo de producci\u00f3n.<\/p><\/li><li data-start=\"2307\" data-end=\"2436\"><p data-start=\"2309\" data-end=\"2436\"><a href=\"https:\/\/www.verdantis.com\/bom-management\/\"><strong data-start=\"2309\" data-end=\"2338\">Listas de materiales<\/strong><\/a> dependen de la precisi\u00f3n del maestro de art\u00edculos. Si los n\u00fameros de pieza se gestionan mal, se alteran los plazos de producci\u00f3n.<\/p><\/li><li data-start=\"2437\" data-end=\"2568\"><p data-start=\"2439\" data-end=\"2568\"><strong data-start=\"2439\" data-end=\"2465\">Optimizaci\u00f3n log\u00edstica<\/strong> requiere conocer el tama\u00f1o, el peso y los requisitos de manipulaci\u00f3n de los art\u00edculos, todo ello almacenado en el maestro de art\u00edculos.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81de0df e-con-full e-flex e-con e-parent\" data-id=\"81de0df\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1cdfa7 elementor-widget elementor-widget-heading\" data-id=\"c1cdfa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"maintenance-operations-especially-in-manufacturing-asset-intensive-industries\">Operaciones de mantenimiento (especialmente en industrias manufactureras y de uso intensivo de activos)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff6bab elementor-widget elementor-widget-text-editor\" data-id=\"1ff6bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"2999\" data-end=\"3156\"><p data-start=\"3001\" data-end=\"3156\"><strong data-start=\"3001\" data-end=\"3031\">Identificaci\u00f3n de piezas de recambio<\/strong> durante el mantenimiento preventivo o correctivo requiere claridad. Los datos incorrectos pueden provocar retrasos o la expedici\u00f3n de piezas equivocadas.<\/p><\/li><li data-start=\"3157\" data-end=\"3253\"><p data-start=\"3159\" data-end=\"3253\"><strong data-start=\"3159\" data-end=\"3188\">Vinculaci\u00f3n con las listas de materiales de los equipos<\/strong> garantiza que los t\u00e9cnicos puedan encontrar y solicitar r\u00e1pidamente la pieza adecuada.<\/p><\/li><li data-start=\"3254\" data-end=\"3359\"><p data-start=\"3256\" data-end=\"3359\"><strong data-start=\"3256\" data-end=\"3294\">Indicadores de criticidad y niveles de existencias<\/strong> ayudar a priorizar el almacenamiento de repuestos esenciales para reducir el tiempo de inactividad.<\/p><\/li><li data-start=\"3360\" data-end=\"3449\"><p data-start=\"3362\" data-end=\"3449\"><strong data-start=\"3362\" data-end=\"3409\">Referencias cruzadas de las referencias de los fabricantes<\/strong> facilita el abastecimiento r\u00e1pido en caso de emergencia.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7635de3 e-flex e-con-boxed e-con e-parent\" data-id=\"7635de3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0923b09 elementor-widget elementor-widget-heading\" data-id=\"0923b09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"background-of-item-master-data\">Antecedentes de los datos maestros de art\u00edculos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2511854 elementor-widget elementor-widget-text-editor\" data-id=\"2511854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los datos maestros de art\u00edculos constituyen la columna vertebral de las operaciones de Oracle ERP, ya que contienen informaci\u00f3n esencial sobre cada producto que una empresa compra, fabrica o vende. Garantiza la coherencia entre m\u00f3dulos como aprovisionamiento, inventario y fabricaci\u00f3n, lo que permite realizar transacciones precisas y tomar decisiones eficientes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5fdf7b e-flex e-con-boxed e-con e-parent\" data-id=\"a5fdf7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2794de9 elementor-widget elementor-widget-heading\" data-id=\"2794de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"item-templates\">Plantillas de art\u00edculos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a017f7b e-flex e-con-boxed e-con e-parent\" data-id=\"a017f7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ce96f elementor-widget elementor-widget-text-editor\" data-id=\"c5ce96f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"268\" data-end=\"562\">Al crear art\u00edculos en Oracle, hay cientos de atributos que rellenar, desde controles de inventario hasta m\u00e9todos de c\u00e1lculo de costes. Ah\u00ed es donde entran en juego las plantillas. Las plantillas de art\u00edculos act\u00faan como conjuntos preconfigurados de atributos por defecto. Simplifican el proceso y reducen los errores al garantizar la coherencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af24353 elementor-widget elementor-widget-text-editor\" data-id=\"af24353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul data-start=\"564\" data-end=\"1118\"><li data-start=\"564\" data-end=\"724\"><p data-start=\"566\" data-end=\"724\"><strong data-start=\"566\" data-end=\"592\">Plantilla Finished Good<\/strong>: Se utiliza cuando se crean art\u00edculos fabricados y vendibles. Establece valores por defecto para WIP (trabajo en curso), c\u00e1lculo de costes y atributos de venta.<\/p><\/li><li data-start=\"725\" data-end=\"883\"><p data-start=\"727\" data-end=\"883\"><strong data-start=\"727\" data-end=\"754\">Plantilla de art\u00edculos comprados<\/strong>: \u00datil para art\u00edculos que se compran a proveedores. Desactiva los indicadores relacionados con la fabricaci\u00f3n y activa los relacionados con el aprovisionamiento.<\/p><\/li><li data-start=\"884\" data-end=\"1004\"><p data-start=\"886\" data-end=\"1004\"><strong data-start=\"886\" data-end=\"908\">Hacer plantilla de art\u00edculo<\/strong>: Se centra en la fabricaci\u00f3n interna. Establece indicadores para hojas de ruta, \u00f3rdenes de trabajo y asociaciones de listas de materiales.<\/p><\/li><li data-start=\"1005\" data-end=\"1118\"><p data-start=\"1007\" data-end=\"1118\"><strong data-start=\"1007\" data-end=\"1034\">Plantilla de art\u00edculos del inventario<\/strong>: Plantilla b\u00e1sica para art\u00edculos almacenados en existencias pero no necesariamente vendidos o fabricados.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf55b54 e-flex e-con-boxed e-con e-parent\" data-id=\"cf55b54\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46dddda elementor-widget elementor-widget-image\" data-id=\"46dddda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Templates-Hierarchy.png\" class=\"attachment-large size-large wp-image-33541\" alt=\"Una imagen que muestra la jerarqu\u00eda en Plantillas de art\u00edculos\" srcset=\"https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Templates-Hierarchy.png 1024w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Templates-Hierarchy-300x225.png 300w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Templates-Hierarchy-768x576.png 768w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Templates-Hierarchy-16x12.png 16w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c192bd e-flex e-con-boxed e-con e-parent\" data-id=\"1c192bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-957ad97 elementor-widget elementor-widget-heading\" data-id=\"957ad97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"cross-references-and-catalogs\">Referencias cruzadas y cat\u00e1logos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-659bf70 e-flex e-con-boxed e-con e-parent\" data-id=\"659bf70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cba6f84 elementor-widget elementor-widget-text-editor\" data-id=\"cba6f84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1378\" data-end=\"1517\">Los sistemas Oracle suelen tratar con m\u00faltiples partes interesadas, cada una de las cuales utiliza sus propios c\u00f3digos para el mismo art\u00edculo. Las referencias cruzadas hacen que esto sea manejable.<\/p><ul data-start=\"1519\" data-end=\"2314\"><li data-start=\"1519\" data-end=\"1730\"><p data-start=\"1521\" data-end=\"1730\"><strong data-start=\"1521\" data-end=\"1546\">N\u00fameros de art\u00edculo del cliente<\/strong>: Los representantes de ventas pueden necesitar tomar pedidos utilizando la convenci\u00f3n de nomenclatura de un cliente. Esta asignaci\u00f3n garantiza que el art\u00edculo interno se identifique correctamente cuando un cliente haga referencia a \"Pieza XZ-789\".<\/p><\/li><li data-start=\"1731\" data-end=\"1938\"><p data-start=\"1733\" data-end=\"1938\"><strong data-start=\"1733\" data-end=\"1758\">Proveedor N\u00fameros de art\u00edculo<\/strong>: Al generar pedidos, los equipos de compras pueden hacer referencia al c\u00f3digo de art\u00edculo de un proveedor, aunque Oracle utilice un c\u00f3digo interno diferente. Esto garantiza la claridad del pedido y reduce la confusi\u00f3n.<\/p><\/li><li data-start=\"1939\" data-end=\"2113\"><p data-start=\"1941\" data-end=\"2113\"><strong data-start=\"1941\" data-end=\"1970\">N\u00fameros de pieza del fabricante<\/strong>: Ayuda a la trazabilidad, especialmente en industrias como la aeroespacial o la electr\u00f3nica, en las que hay que seguir la pista a componentes de distintos fabricantes.<\/p><\/li><li data-start=\"2114\" data-end=\"2314\"><p data-start=\"2116\" data-end=\"2314\"><strong data-start=\"2116\" data-end=\"2143\">Cat\u00e1logos y categor\u00edas<\/strong>: Organizan los art\u00edculos de forma que sea m\u00e1s f\u00e1cil buscarlos y agruparlos, lo que resulta especialmente \u00fatil en sistemas de aprovisionamiento de autoservicio, plataformas de comercio electr\u00f3nico o entornos MRO.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-143c3aa elementor-widget elementor-widget-text-editor\" data-id=\"143c3aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2316\" data-end=\"2421\">En \u00faltima instancia, las referencias cruzadas reducen los errores humanos y agilizan la comunicaci\u00f3n entre sistemas y socios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a8e4ac e-flex e-con-boxed e-con e-parent\" data-id=\"5a8e4ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17e38c6 elementor-widget elementor-widget-heading\" data-id=\"17e38c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"item-categories-and-catalogs\">Categor\u00edas de art\u00edculos y cat\u00e1logos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86ee154 e-flex e-con-boxed e-con e-parent\" data-id=\"86ee154\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-413937b elementor-widget elementor-widget-text-editor\" data-id=\"413937b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2468\" data-end=\"2658\">No todos los art\u00edculos se gestionan de la misma manera. Algunos son materiales directos, otros son suministros MRO. Oracle le permite segmentar los art\u00edculos utilizando <strong data-start=\"2596\" data-end=\"2613\">Conjuntos de categor\u00edas<\/strong>y cada conjunto puede servir para un fin distinto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f74bc elementor-widget elementor-widget-text-editor\" data-id=\"a2f74bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul data-start=\"2660\" data-end=\"3028\"><li data-start=\"2660\" data-end=\"2794\"><p data-start=\"2662\" data-end=\"2794\"><strong data-start=\"2662\" data-end=\"2675\">Buscar en<\/strong>: Los usuarios pueden encontrar las piezas m\u00e1s f\u00e1cilmente cuando est\u00e1n organizadas en categor\u00edas significativas (por ejemplo, Rodamientos &gt; Rodamientos de bolas).<\/p><\/li><li data-start=\"2795\" data-end=\"2898\"><p data-start=\"2797\" data-end=\"2898\"><strong data-start=\"2797\" data-end=\"2810\">Informes<\/strong>: Los informes de gastos, los rollups de costes o los an\u00e1lisis de inventarios antiguos suelen dividir los datos por categor\u00edas.<\/p><\/li><li data-start=\"2899\" data-end=\"3028\"><p data-start=\"2901\" data-end=\"3028\"><strong data-start=\"2901\" data-end=\"2925\">Planificaci\u00f3n\/Adquisici\u00f3n<\/strong>: Las previsiones o los niveles de stock de seguridad pueden aplicarse de forma diferente para \"Materias primas\" y para \"Piezas de recambio\".<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01eb510 elementor-widget elementor-widget-text-editor\" data-id=\"01eb510\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3030\" data-end=\"3267\">Puede tener varios conjuntos de categor\u00edas: una categor\u00eda de compras puede centrarse en la estrategia de proveedores, mientras que una categor\u00eda de costes ayuda a asignar costes. Esta segmentaci\u00f3n es poderosa y esencial para las grandes empresas con cadenas de suministro complejas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee43c65 e-flex e-con-boxed e-con e-parent\" data-id=\"ee43c65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e5eba8 elementor-widget elementor-widget-heading\" data-id=\"3e5eba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"item-relationship\">Art\u00edculo Relaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4eeb357 e-flex e-con-boxed e-con e-parent\" data-id=\"4eeb357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebc19c6 elementor-widget elementor-widget-text-editor\" data-id=\"ebc19c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3304\" data-end=\"3420\">Los art\u00edculos no existen de forma aislada: a menudo est\u00e1n vinculados a otros con fines operativos, de planificaci\u00f3n o de sustituci\u00f3n.<\/p><ul data-start=\"3422\" data-end=\"4035\"><li data-start=\"3422\" data-end=\"3605\"><p data-start=\"3424\" data-end=\"3605\"><strong data-start=\"3424\" data-end=\"3439\">Sustitutos<\/strong>: Si un art\u00edculo est\u00e1 agotado, se puede sugerir autom\u00e1ticamente su sustituto en los sistemas de entrada de pedidos o planificaci\u00f3n. Esto ayuda a mantener los niveles de servicio durante las interrupciones.<\/p><\/li><li data-start=\"3606\" data-end=\"3803\"><p data-start=\"3608\" data-end=\"3803\"><strong data-start=\"3608\" data-end=\"3628\">Art\u00edculos sustituidos<\/strong>: Con el tiempo, los art\u00edculos se quedan obsoletos y se sustituyen. Oracle mantiene este linaje para que los registros hist\u00f3ricos sigan siendo v\u00e1lidos, mientras que la planificaci\u00f3n y el aprovisionamiento pasan a la nueva pieza.<\/p><\/li><li data-start=\"3804\" data-end=\"4035\"><p data-start=\"3806\" data-end=\"4035\"><strong data-start=\"3806\" data-end=\"3825\">Co-\/By-productos<\/strong>: En la fabricaci\u00f3n por procesos (por ejemplo, alimentos, productos qu\u00edmicos), la fabricaci\u00f3n de un art\u00edculo a menudo produce otros. Oracle permite definir coproductos (planificados, valiosos) y subproductos (secundarios, tal vez reciclables) durante la configuraci\u00f3n de la receta.<\/p><\/li><\/ul><p data-start=\"4037\" data-end=\"4142\">Estas relaciones son fundamentales para la precisi\u00f3n de la planificaci\u00f3n, la disponibilidad de las existencias y la gesti\u00f3n del ciclo de vida.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dfdf787 e-flex e-con-boxed e-con e-parent\" data-id=\"dfdf787\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79a9747 elementor-widget elementor-widget-heading\" data-id=\"79a9747\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"item-lifecycle-status-control\">Control del ciclo de vida y del estado de los art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94cc9cd e-flex e-con-boxed e-con e-parent\" data-id=\"94cc9cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f67571 elementor-widget elementor-widget-text-editor\" data-id=\"7f67571\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"4194\" data-end=\"4275\">Los estados de los art\u00edculos dictan lo que se puede y no se puede hacer con un producto en un momento dado.<\/p><ul data-start=\"4277\" data-end=\"4842\"><li data-start=\"4277\" data-end=\"4491\"><p data-start=\"4279\" data-end=\"4491\"><strong data-start=\"4279\" data-end=\"4300\">C\u00f3digos de estado de los art\u00edculos<\/strong>: Ayuda a indicar en qu\u00e9 punto del ciclo de vida se encuentra el elemento: por ejemplo, \"Nuevo\" (a\u00fan no aprobado), \"Activo\" (disponible para transacciones) u \"Obsoleto\" (bloqueado para nuevos usos pero a\u00fan notificable).<\/p><\/li><li data-start=\"4492\" data-end=\"4647\"><p data-start=\"4494\" data-end=\"4647\"><strong data-start=\"4494\" data-end=\"4513\">Controles de estado<\/strong>: Determine d\u00f3nde se puede utilizar el art\u00edculo: puede que est\u00e9 permitido en el inventario pero no en las ventas, o que se pueda comprar pero no fabricar.<\/p><\/li><li data-start=\"4648\" data-end=\"4842\"><p data-start=\"4650\" data-end=\"4842\"><strong data-start=\"4650\" data-end=\"4669\">Integraci\u00f3n PLM<\/strong>: Al utilizar Oracle Product Lifecycle Management, los cambios de estado (como \"Dise\u00f1o finalizado\" o \"Liberado para fabricaci\u00f3n\") fluyen autom\u00e1ticamente a los sistemas de inventario y lista de materiales.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cb22f9 elementor-widget elementor-widget-text-editor\" data-id=\"6cb22f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"4844\" data-end=\"4975\">Esto garantiza que ingenier\u00eda, compras y operaciones est\u00e9n siempre alineadas, y que los art\u00edculos obsoletos no se cuelen en las series de producci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6680533 e-flex e-con-boxed e-con e-parent\" data-id=\"6680533\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9445293 elementor-widget elementor-widget-heading\" data-id=\"9445293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"how-item-master-data-is-created\">C\u00f3mo se crean los datos maestros de art\u00edculos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0dcd24 e-flex e-con-boxed e-con e-parent\" data-id=\"b0dcd24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94a227a elementor-widget elementor-widget-text-editor\" data-id=\"94a227a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"4194\" data-end=\"4275\">El proceso de datos maestros de art\u00edculos comienza con la captura de detalles clave como el nombre del art\u00edculo, el tipo y la unidad de medida. A partir de ah\u00ed, se aplican plantillas para rellenar autom\u00e1ticamente los atributos est\u00e1ndar y se clasifica el art\u00edculo para su uso en inventario, compras o planificaci\u00f3n.<\/p><p data-start=\"4194\" data-end=\"4275\">Los flujos de trabajo de aprobaci\u00f3n y las validaciones garantizan que los datos sean precisos y est\u00e9n completos antes de que el art\u00edculo est\u00e9 disponible en todos los m\u00f3dulos de Oracle ERP.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4e8bbb e-flex e-con-boxed e-con e-parent\" data-id=\"d4e8bbb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eac6daa elementor-widget elementor-widget-heading\" data-id=\"eac6daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-1-item-request-input-start-point\">Paso 1: Introducci\u00f3n de la solicitud de art\u00edculo (punto de partida)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-359eaca e-flex e-con-boxed e-con e-parent\" data-id=\"359eaca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9a1206 elementor-widget elementor-widget-text-editor\" data-id=\"f9a1206\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta es la etapa inicial en la que se capturan e introducen en el sistema los datos relacionados con los art\u00edculos.<\/p><p>Los datos pueden proceder de m\u00faltiples fuentes, como equipos de compras, equipos de proyectos, ingenier\u00eda, dise\u00f1o, proveedores, departamentos de fabricaci\u00f3n y sistemas externos de terceros.<\/p><p>Los datos recogidos en esta fase incluyen:<\/p><ul><li><p><strong data-start=\"597\" data-end=\"623\">Especificaciones del producto<\/strong>: Caracter\u00edsticas t\u00e9cnicas, tama\u00f1o, peso, materiales utilizados, etc.<\/p><\/li><li><p><strong data-start=\"691\" data-end=\"712\">Descripci\u00f3n de los art\u00edculos<\/strong>: Descripciones detalladas que identifiquen con precisi\u00f3n el art\u00edculo.<\/p><\/li><li><p><strong data-start=\"775\" data-end=\"786\">Precios<\/strong>: Informaci\u00f3n sobre costes y estrategias de fijaci\u00f3n de precios.<\/p><\/li><li><p><strong data-start=\"836\" data-end=\"861\">Unidad de medida (UM)<\/strong>: Unidad en la que se mide el art\u00edculo, como kg, metros, litros, etc.<\/p><\/li><li><p><strong data-start=\"940\" data-end=\"958\">Clasificaci\u00f3n<\/strong>: Categorizaci\u00f3n de art\u00edculos mediante sistemas de clasificaci\u00f3n internos o sistemas de codificaci\u00f3n est\u00e1ndar (por ejemplo, UNSPSC, eCl@ss).<\/p><\/li><\/ul><p>Enriquecimiento de datos: Complementaci\u00f3n de los datos iniciales con atributos que faltan (por ejemplo, informaci\u00f3n del proveedor, c\u00f3digos del fabricante) que pueden no estar incluidos en la entrada inicial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-897821d e-flex e-con-boxed e-con e-parent\" data-id=\"897821d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9be27f6 elementor-widget elementor-widget-heading\" data-id=\"9be27f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-2-item-staging-tables\">Paso 2: Tablas de clasificaci\u00f3n de art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a73184 e-flex e-con-boxed e-con e-parent\" data-id=\"7a73184\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea23958 elementor-widget elementor-widget-text-editor\" data-id=\"ea23958\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tras la introducci\u00f3n inicial de datos, la informaci\u00f3n se almacena temporalmente en <span data-start=\"1343\" data-end=\"1361\">mesas de montaje<\/span> para realizar comprobaciones preliminares de validaci\u00f3n antes de la integraci\u00f3n en el sistema activo.<\/p><ul data-start=\"1270\" data-end=\"1915\"><li data-start=\"1444\" data-end=\"1599\"><p><strong>Funci\u00f3n de b\u00fafer:<\/strong> Las tablas de preparaci\u00f3n act\u00faan como una zona de espera temporal que permite al sistema validar y limpiar los datos antes de que entren en los entornos de producci\u00f3n.<\/p><\/li><li data-start=\"1600\" data-end=\"1734\"><p><strong>Garant\u00eda de calidad de los datos:<\/strong> Comprobaciones iniciales para identificar campos que faltan, errores de formato e incoherencias entre distintas fuentes.<\/p><\/li><li data-start=\"1735\" data-end=\"1912\"><p><strong>Optimizaci\u00f3n del rendimiento:<\/strong> Los datos de las tablas de preparaci\u00f3n se optimizan para su procesamiento, lo que mejora el rendimiento del sistema y permite el procesamiento paralelo de varios registros.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4e4a62 e-flex e-con-boxed e-con e-parent\" data-id=\"a4e4a62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-078f9b7 elementor-widget elementor-widget-heading\" data-id=\"078f9b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-3-item-data-processing\">Paso 3: Procesamiento de datos de art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a7399a5 e-flex e-con-boxed e-con e-parent\" data-id=\"a7399a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6f2f11 elementor-widget elementor-widget-text-editor\" data-id=\"e6f2f11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los datos de las tablas de preparaci\u00f3n se someten a una amplia validaci\u00f3n, enriquecimiento y normalizaci\u00f3n para garantizar la coherencia y la calidad de los datos.<\/p><p><strong data-start=\"2083\" data-end=\"2102\">Validaci\u00f3n de datos<\/strong>: Garantizar que todos los campos obligatorios se rellenan y respetan los formatos definidos (por ejemplo, formatos de fecha, valores num\u00e9ricos).<\/p><p><strong data-start=\"2218\" data-end=\"2232\">Enriquecimiento<\/strong>: A\u00f1adir informaci\u00f3n adicional cuando sea necesario (por ejemplo, atributos espec\u00edficos del proveedor, referencias cruzadas de datos procedentes de fuentes externas).<\/p><p><strong data-start=\"2365\" data-end=\"2384\">Normalizaci\u00f3n de datos<\/strong>:<\/p><ul><li><p><strong data-start=\"2390\" data-end=\"2416\">Asignaci\u00f3n de categor\u00edas<\/strong>: Los art\u00edculos se asignan a las categor\u00edas internas y normas de clasificaci\u00f3n apropiadas.<\/p><\/li><li><p><strong data-start=\"2508\" data-end=\"2548\">Normalizaci\u00f3n de divisas y precios<\/strong>: Garantizar que la informaci\u00f3n sobre precios se ajusta a los c\u00f3digos de divisas y a las horquillas de precios v\u00e1lidas.<\/p><\/li><li><p><strong data-start=\"2639\" data-end=\"2662\">Detecci\u00f3n de duplicados<\/strong>: Ejecuci\u00f3n de algoritmos para identificar y fusionar registros duplicados en funci\u00f3n de criterios predefinidos (por ejemplo, descripci\u00f3n del art\u00edculo, n\u00fameros de pieza del fabricante).<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75e624e e-flex e-con-boxed e-con e-parent\" data-id=\"75e624e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5564e6d elementor-widget elementor-widget-heading\" data-id=\"5564e6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-4-item-loader-staging-tables\">Paso 4: Tablas de puesta a disposici\u00f3n del cargador de art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b7aeea e-flex e-con-boxed e-con e-parent\" data-id=\"3b7aeea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b59f1cd elementor-widget elementor-widget-text-editor\" data-id=\"b59f1cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una vez que los datos han superado la validaci\u00f3n preliminar en la puesta en escena, se transfieren a <strong data-start=\"2926\" data-end=\"2956\">Cargador de art\u00edculos Mesas de puesta a disposici\u00f3n<\/strong>una etapa intermedia en la que se realizan comprobaciones adicionales m\u00e1s exhaustivas.<\/p><p><strong data-start=\"3040\" data-end=\"3073\">Comprobaci\u00f3n de calidad previa a la integraci\u00f3n<\/strong>: Las tablas de etapas del cargador permiten una validaci\u00f3n m\u00e1s rigurosa, como:<\/p><ul><li><p>Comprobaci\u00f3n cruzada con datos de referencia externos (por ejemplo, cat\u00e1logos de productos existentes, sistemas de clasificaci\u00f3n).<\/p><\/li><li><p>Verificaci\u00f3n contra <strong data-start=\"3280\" data-end=\"3332\">Maestro de art\u00edculos EIP (Puntos de Integraci\u00f3n Empresarial)<\/strong> para garantizar la coherencia con las fuentes de datos externas.<\/p><\/li><\/ul><p><strong data-start=\"3379\" data-end=\"3419\">Integraci\u00f3n con sistemas de terceros<\/strong>: Garantiza una sincronizaci\u00f3n perfecta de los datos con los sistemas externos (por ejemplo, alimentaci\u00f3n de datos de proveedores, bases de datos de ingenier\u00eda).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8ea50d e-flex e-con-boxed e-con e-parent\" data-id=\"f8ea50d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c55a47 elementor-widget elementor-widget-image\" data-id=\"6c55a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"602\" height=\"545\" src=\"https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Master-Data-Background.jpg\" class=\"attachment-large size-large wp-image-27787\" alt=\"\" srcset=\"https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Master-Data-Background.jpg 602w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Master-Data-Background-300x272.jpg 300w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Master-Data-Background-150x136.jpg 150w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-98b2320 e-flex e-con-boxed e-con e-parent\" data-id=\"98b2320\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e6d158 elementor-widget elementor-widget-heading\" data-id=\"9e6d158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-5-item-loader-process\">Paso 5: Proceso de carga de art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9ae09b0 e-flex e-con-boxed e-con e-parent\" data-id=\"9ae09b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cb8228 elementor-widget elementor-widget-text-editor\" data-id=\"5cb8228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El proceso de carga de elementos automatiza la transferencia de datos validados, enriquecidos y estructurados desde la zona de preparaci\u00f3n a los sistemas operativos en tiempo real. Sigue como:<\/p><ul><li><p><strong>Automatizaci\u00f3n y programaci\u00f3n:<\/strong> Este paso suele automatizarse para que se ejecute peri\u00f3dicamente o en funci\u00f3n de calendarios predefinidos para garantizar la integraci\u00f3n de datos en tiempo real sin intervenci\u00f3n manual.<\/p><\/li><li><p><strong>Mapeo y transformaci\u00f3n de datos:<\/strong> El cargador garantiza que los datos se asignan correctamente a las tablas de producci\u00f3n finales y que los formatos de datos se transforman para cumplir los requisitos del sistema (por ejemplo, conversi\u00f3n de unidades de medida, conversi\u00f3n de valores monetarios).<\/p><\/li><li><p><strong>Registro de errores:<\/strong> Cualquier discrepancia o problema que surja durante el proceso de carga se registra en la tabla de errores para su posterior investigaci\u00f3n y resoluci\u00f3n.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff0aa31 e-flex e-con-boxed e-con e-parent\" data-id=\"ff0aa31\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4114c0 elementor-widget elementor-widget-heading\" data-id=\"b4114c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-6-error-tables\">Paso 6: Tablas de errores<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81526eb e-flex e-con-boxed e-con e-parent\" data-id=\"81526eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9212941 elementor-widget elementor-widget-text-editor\" data-id=\"9212941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En <strong data-start=\"4353\" data-end=\"4368\">Tabla de errores<\/strong> act\u00faa como registro y repositorio de los elementos que no se han podido cargar correctamente en el sistema activo.<\/p><p><strong data-start=\"4470\" data-end=\"4489\">Tipos de errores<\/strong>:<\/p><ul><li><p>Datos incompletos o que faltan (por ejemplo, detalles del proveedor, precios o campos obligatorios).<\/p><\/li><li><p>Valores no v\u00e1lidos o fuera de rango (por ejemplo, incoherencias en los precios, UM err\u00f3neas).<\/p><\/li><li><p>Infracciones del formato de los datos (por ejemplo, formato de fecha incorrecto, n\u00fameros de pieza no v\u00e1lidos).<\/p><\/li><\/ul><p><strong data-start=\"4748\" data-end=\"4768\">Correcci\u00f3n de errores<\/strong>: Los errores en los datos deben identificarse, corregirse y probarse antes de volver a intentar cargarlos en los sistemas de producci\u00f3n.<\/p><p><strong data-start=\"4881\" data-end=\"4901\">Alertas autom\u00e1ticas<\/strong>: El sistema puede configurarse para activar notificaciones autom\u00e1ticas o flujos de trabajo cuando se registran errores, lo que mejora los tiempos de respuesta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58fa4f8 e-flex e-con-boxed e-con e-parent\" data-id=\"58fa4f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf45f5 elementor-widget elementor-widget-heading\" data-id=\"4cf45f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-7-final-production-tables\">Paso 7: Tablas de producci\u00f3n finales<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-828e49e e-flex e-con-boxed e-con e-parent\" data-id=\"828e49e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46e8d19 elementor-widget elementor-widget-text-editor\" data-id=\"46e8d19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una vez que los datos de los art\u00edculos se someten a todas las validaciones y comprobaciones de calidad, se fusionan en el archivo <strong>Tablas finales de producci\u00f3n.<\/strong><\/p><p><strong>Acceso a todo el sistema:<\/strong> Los datos de los art\u00edculos completados se almacenan en la base de datos central, a disposici\u00f3n de diferentes funciones empresariales como:<\/p><ul><li><p><strong>Compras y adquisiciones:<\/strong> Proporcionar informaci\u00f3n precisa y actualizada sobre los productos para su compra.<\/p><\/li><li><p><strong>Gesti\u00f3n de inventarios:<\/strong> Apoyo a la planificaci\u00f3n, el seguimiento y la elaboraci\u00f3n de informes de inventario.<\/p><\/li><li><p><strong>Ventas y distribuci\u00f3n:<\/strong> Proporcionar a los equipos de ventas informaci\u00f3n precisa sobre los productos para la captaci\u00f3n de clientes.<\/p><\/li><li><p><strong>Gesti\u00f3n de las relaciones con los proveedores:<\/strong> Simplificaci\u00f3n de la comunicaci\u00f3n y la interacci\u00f3n con los proveedores sobre la base de los registros de art\u00edculos m\u00e1s precisos.<\/p><\/li><li><p><strong>Ingenier\u00eda y fabricaci\u00f3n:<\/strong> Suministro de especificaciones de productos fundamentales para la producci\u00f3n y la gesti\u00f3n del ciclo de vida de los productos.<\/p><\/li><\/ul><p><strong>Gobernanza de datos:<\/strong> Garantiza que los datos de producci\u00f3n finales se ajustan a las pol\u00edticas de gobernanza de datos de la empresa, como propiedad, control de acceso y auditor\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7927e3 e-flex e-con-boxed e-con e-parent\" data-id=\"b7927e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-930b8ca elementor-widget elementor-widget-heading\" data-id=\"930b8ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"step-8-item-master-eips-external-data-reference\">Paso 8: Maestro de art\u00edculos EIP (Referencia externa de datos)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3889b42 e-flex e-con-boxed e-con e-parent\" data-id=\"3889b42\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcaa815 elementor-widget elementor-widget-text-editor\" data-id=\"fcaa815\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los Puntos de Integraci\u00f3n Empresarial (PIE) son fuentes externas de datos que act\u00faan como punto de referencia para mantener la coherencia y exactitud de la informaci\u00f3n de los elementos en toda la organizaci\u00f3n. Los PIE importantes son:<\/p><ul><li><p><strong>Datos proporcionados por el proveedor:<\/strong> Cat\u00e1logos de proveedores y especificaciones de productos que aumentan los datos internos de los art\u00edculos.<\/p><\/li><li><p><strong>Actualizaciones de la gesti\u00f3n de cambios de ingenier\u00eda (ECM):<\/strong> Sistemas externos que informan de los cambios de dise\u00f1o o las nuevas especificaciones de los art\u00edculos.<\/p><\/li><li><p><strong>Normas de clasificaci\u00f3n industrial:<\/strong> Asegurarse de que los art\u00edculos cumplen normas de clasificaci\u00f3n externas como UNSPSC, eCl@ss, PIDX o la codificaci\u00f3n de art\u00edculos basada en ISO para garantizar la coherencia entre sectores.<\/p><\/li><\/ul><p><strong>Sincronizaci\u00f3n de datos:<\/strong> Las EIP permiten sincronizar los datos de los art\u00edculos con cat\u00e1logos y repositorios de datos externos, lo que proporciona actualizaciones en tiempo real y la incorporaci\u00f3n de la informaci\u00f3n m\u00e1s actualizada sobre los productos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf6379b e-con-full e-flex e-con e-parent\" data-id=\"cf6379b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08ed15d elementor-widget elementor-widget-heading\" data-id=\"08ed15d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"item-master-vs-inventory-master-vs-material-master\">Maestro de art\u00edculos vs. Maestro de inventario vs. Maestro de materiales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35ae69a elementor-widget elementor-widget-text-editor\" data-id=\"35ae69a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Item Master:<\/strong> Se centra en los detalles completos de un art\u00edculo, incluidas especificaciones, precios, proveedores y descripciones.<\/p><\/li><li><p><strong>Maestro de Inventario:<\/strong> Se ocupa de los niveles de existencias, la ubicaci\u00f3n de los almacenes y la disponibilidad actual de los art\u00edculos del inventario.<\/p><\/li><li><p><strong>Material Master:<\/strong> Abarca los materiales utilizados en los procesos de fabricaci\u00f3n, incluidas las materias primas, los productos en curso y los productos acabados.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f955866 e-con-full e-flex e-con e-parent\" data-id=\"f955866\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f950dc4 elementor-widget elementor-widget-heading\" data-id=\"f950dc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Calidad de los datos maestros de art\u00edculos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2bb23c elementor-widget elementor-widget-text-editor\" data-id=\"a2bb23c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Fuente \u00fanica de la verdad:<\/strong> Garantiza la coherencia y exactitud de los datos relativos a los art\u00edculos en todos los departamentos.<\/p><\/li><li><p><strong>Consecuencias de la mala calidad de los datos:<\/strong> Conduce a ineficiencias, errores operativos, roturas de stock, exceso de existencias, procesos de compra ineficientes que provocan p\u00e9rdidas financieras.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cb93d6 e-con-full e-flex e-con e-parent\" data-id=\"7cb93d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35f2b7a elementor-widget elementor-widget-heading\" data-id=\"35f2b7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gesti\u00f3n de datos de roles maestros de art\u00edculos (MDM)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3701c58 elementor-widget elementor-widget-text-editor\" data-id=\"3701c58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>An\u00e1lisis del ciclo de vida del producto:<\/strong> Realiza un seguimiento del ciclo de vida de los productos desde su creaci\u00f3n hasta su obsolescencia, lo que permite tomar decisiones a tiempo.<\/p><\/li><li><p><strong>Usuarios directos:<\/strong> Equipos de compras, gesti\u00f3n de la cadena de suministro, fabricantes y gesti\u00f3n de inventarios.<\/p><\/li><li><p><strong>Usuarios indirectos:<\/strong> Planificaci\u00f3n de las necesidades de materiales, gesti\u00f3n de las relaciones con los proveedores y equipos de ingenier\u00eda.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b493e3 e-flex e-con-boxed e-con e-parent\" data-id=\"6b493e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5eb76 elementor-widget elementor-widget-heading\" data-id=\"3f5eb76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"item-master-important-attributes\">Maestro de art\u00edculos - Atributos importantes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65b8d6e e-flex e-con-boxed e-con e-parent\" data-id=\"65b8d6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d24c593 elementor-widget elementor-widget-text-editor\" data-id=\"d24c593\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los datos maestros de art\u00edculos constan de varios atributos que definen y categorizan cada art\u00edculo de forma estructurada. Estos atributos ayudan a gestionar eficazmente el inventario, el aprovisionamiento y el seguimiento del ciclo de vida del producto. A continuaci\u00f3n se indican los componentes clave:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43b7df7 e-flex e-con-boxed e-con e-parent\" data-id=\"43b7df7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a0a1a4 elementor-widget elementor-widget-heading\" data-id=\"4a0a1a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"structure-of-item-master\">Estructura del maestro de art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96b011b e-flex e-con-boxed e-con e-parent\" data-id=\"96b011b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f54917 elementor-widget elementor-widget-text-editor\" data-id=\"2f54917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En <strong>Item Master<\/strong> sigue un formato estructurado que garantiza la uniformidad de todos los elementos de la base de datos.<\/p><p>Se clasifica en una jerarqu\u00eda de <strong>categor\u00edas principales y subcategor\u00edas<\/strong> basados en caracter\u00edsticas compartidas.<\/p><p>Los atributos clave incluyen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d14342 e-con-full e-flex e-con e-parent\" data-id=\"0d14342\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bd81f1 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4bd81f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewbox=\"0 0 64 64\" data-name=\"Layer 1\"><path d=\"m52.5 2.14h-23.37c-3.33 0-6.05 2.72-6.05 6.05s2.72 6.05 6.05 6.05h23.37c3.33 0 6.05-2.71 6.05-6.05s-2.72-6.05-6.05-6.05zm0 10.1h-23.37c-2.23 0-4.05-1.82-4.05-4.05s1.82-4.05 4.05-4.05h23.37c2.23 0 4.05 1.82 4.05 4.05s-1.82 4.05-4.05 4.05z\"><\/path><path d=\"m52.5 17.89h-23.37c-3.33 0-6.05 2.72-6.05 6.05s2.72 6.05 6.05 6.05h23.37c3.33 0 6.05-2.71 6.05-6.05s-2.72-6.05-6.05-6.05zm0 10.1h-23.37c-2.23 0-4.05-1.81-4.05-4.05s1.82-4.05 4.05-4.05h23.37c2.23 0 4.05 1.82 4.05 4.05s-1.82 4.05-4.05 4.05z\"><\/path><path d=\"m17.57 8.19c0-3.33-2.72-6.05-6.05-6.05s-6.05 2.72-6.05 6.05c0 3 2.19 5.48 5.05 5.96v3.83c-2.86.48-5.05 2.97-5.05 5.96s2.19 5.48 5.05 5.96v3.84c-2.86.48-5.05 2.97-5.05 5.96s2.19 5.47 5.05 5.95v3.84c-2.86.48-5.05 2.96-5.05 5.96 0 3.33 2.71 6.05 6.05 6.05s6.05-2.72 6.05-6.05c0-3-2.19-5.48-5.05-5.96v-3.84c2.86-.48 5.05-2.96 5.05-5.95s-2.19-5.48-5.05-5.96v-3.84c2.86-.48 5.05-2.97 5.05-5.96s-2.19-5.48-5.05-5.96v-3.83c2.86-.48 5.05-2.97 5.05-5.96z\"><\/path><path d=\"m52.5 33.65h-23.37c-3.33 0-6.05 2.71-6.05 6.05s2.72 6.04 6.05 6.04h23.37c3.33 0 6.05-2.71 6.05-6.04s-2.72-6.05-6.05-6.05zm0 10.09h-23.37c-2.23 0-4.05-1.81-4.05-4.04s1.82-4.05 4.05-4.05h23.37c2.23 0 4.05 1.81 4.05 4.05s-1.82 4.04-4.05 4.04z\"><\/path><path d=\"m52.5 49.4h-23.37c-3.33 0-6.05 2.71-6.05 6.05s2.72 6.05 6.05 6.05h23.37c3.33 0 6.05-2.72 6.05-6.05s-2.72-6.05-6.05-6.05zm0 10.1h-23.37c-2.23 0-4.05-1.82-4.05-4.05s1.82-4.05 4.05-4.05h23.37c2.23 0 4.05 1.81 4.05 4.05s-1.82 4.05-4.05 4.05z\"><\/path><path d=\"m32.646 7.191h-2.129c-.553 0-1 .448-1 1s.447 1 1 1h2.129c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m52.077 7.191h-14.98c-.553 0-1 .448-1 1s.447 1 1 1h14.98c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m32.646 22.94h-2.129c-.553 0-1 .448-1 1s.447 1 1 1h2.129c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m52.077 22.94h-14.98c-.553 0-1 .448-1 1s.447 1 1 1h14.98c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m32.646 38.688h-2.129c-.553 0-1 .448-1 1s.447 1 1 1h2.129c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m52.077 38.688h-14.98c-.553 0-1 .448-1 1s.447 1 1 1h14.98c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m32.646 54.438h-2.129c-.553 0-1 .448-1 1s.447 1 1 1h2.129c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><path d=\"m52.077 54.438h-14.98c-.553 0-1 .448-1 1s.447 1 1 1h14.98c.553 0 1-.448 1-1s-.447-1-1-1z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nombre del art\u00edculo - El nombre est\u00e1ndar del art\u00edculo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"464pt\" viewbox=\"0 0 464 464\" width=\"464pt\"><path d=\"m336 160h16v88h-16zm0 0\"><\/path><path d=\"m288 156.519531-12.246094 6.992188-31.265625-31.265625 2.421875-4.246094h-246.910156v48h288zm-256 3.480469h-16v-16h16zm32 0h-16v-16h16zm32 0h-16v-16h16zm0 0\"><\/path><path d=\"m304 160h16v88h-16zm0 0\"><\/path><path d=\"m345.054688 264h-34.109376l17.054688 25.574219zm0 0\"><\/path><path d=\"m266.832031 98.886719c1.144531 3.699219 2.679688 7.386719 4.574219 10.960937l2.066406 3.878906-9.039062 15.839844 13.980468 13.984375 15.84375-9.039062 9.742188 4.992187v4.496094h48v-4.496094l9.3125-4.785156 4.238281 1.992188 12.023438 6.847656 13.984375-13.984375-9.039063-15.839844 2.066407-3.878906c1.894531-3.574219 3.4375-7.261719 4.574218-10.960938l1.289063-4.191406 17.550781-4.816406v-19.78125l-17.542969-4.808594-1.289062-4.191406c-1.144531-3.699219-2.679688-7.386719-4.574219-10.960938l-2.066406-3.878906 9.039062-15.839844-13.980468-13.984375-15.84375 9.039063-3.878907-2.066407c-3.574219-1.894531-7.261719-3.4375-10.960937-4.574218l-4.191406-1.289063-4.824219-17.550781h-19.78125l-4.808594 17.542969-4.191406 1.289062c-3.699219 1.144531-7.386719 2.679688-10.960938 4.574219l-3.878906 2.066406-15.839844-9.039062-13.984375 13.980468 9.039063 15.84375-2.066407 3.878907c-1.894531 3.574219-3.4375 7.261719-4.574218 10.960937l-1.289063 4.191406-17.550781 4.824219v19.78125l17.542969 4.808594zm61.167969-66.886719c26.472656 0 48 21.527344 48 48s-21.527344 48-48 48-48-21.527344-48-48 21.527344-48 48-48zm0 0\"><\/path><path d=\"m82.34375 301.65625 11.3125-11.3125 17.320312 17.320312 36.902344-51.664062h-75.878906v80h80v-58.230469l-38.976562 54.566407zm0 0\"><\/path><path d=\"m360 80c0 17.671875-14.328125 32-32 32s-32-14.328125-32-32 14.328125-32 32-32 32 14.328125 32 32zm0 0\"><\/path><path d=\"m368 352h-80v80h80zm-10.34375 58.34375-11.3125 11.3125-18.34375-18.34375-18.34375 18.34375-11.3125-11.3125 18.34375-18.34375-18.34375-18.34375 11.3125-11.3125 18.34375 18.34375 18.34375-18.34375 11.3125 11.3125-18.34375 18.34375zm0 0\"><\/path><path d=\"m368 258.425781-40 60-40-60v-66.425781h-288v272h464v-272h-96zm-312-18.425781h103.3125l26.175781-36.648438 13.015625 9.296876-30.503906 42.710937v96.640625h-112zm-40 128h16v16h-16zm160 80h-160v-16h160zm32 0h-16v-16h16zm0-32h-192v-16h192zm0-32h-160v-16h160zm176 64h-112v-112h112zm0 0\"><\/path><path d=\"m409.089844 128 2.421875 4.246094-31.265625 31.265625-12.246094-6.992188v19.480469h96v-48zm0 0\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">C\u00f3digo de art\u00edculo (SKU\/N\u00famero de pieza) - Identificador \u00fanico asignado a cada art\u00edculo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewbox=\"0 0 512 512\" data-name=\"Layer 1\"><path d=\"m460.869 56.708v-33.67l36.062 36.061h-33.675c-1.297 0-2.386-1.094-2.386-2.392zm44.061 18.389v268.957c0 5.723-4.669 10.392-10.391 10.392h-251.857c-5.723 0-10.392-4.668-10.392-10.392v-318.625c0-5.724 4.668-10.392 10.392-10.392h202.185v41.671c0 10.14 8.25 18.389 18.389 18.389zm-176.611 202.017c-3.129-3.124-8.192-3.124-11.321 0l-26.301 26.296-6.986-12.106c-2.213-3.833-7.102-5.14-10.935-2.931-3.819 2.208-5.13 7.097-2.926 10.93l12.208 21.137c1.239 2.15 3.419 3.611 5.882 3.934.347.049.699.068 1.051.068 2.107 0 4.137-.83 5.646-2.339l33.682-33.682c3.12-3.12 3.12-8.192 0-11.306zm0-66.289c-3.129-3.124-8.192-3.124-11.321 0l-26.301 26.301-6.986-12.111c-2.213-3.828-7.102-5.135-10.935-2.932-3.819 2.213-5.13 7.102-2.926 10.93l12.208 21.142c1.239 2.15 3.419 3.606 5.882 3.929.347.048.699.068 1.051.068 2.107 0 4.137-.834 5.646-2.343l33.682-33.673c3.12-3.124 3.12-8.192 0-11.311zm0-66.29c-3.129-3.124-8.192-3.124-11.321 0l-26.301 26.301-6.986-12.111c-2.213-3.823-7.102-5.135-10.935-2.927-3.819 2.208-5.13 7.102-2.926 10.93l12.208 21.137c1.239 2.155 3.419 3.606 5.882 3.929.347.048.699.072 1.051.072 2.107 0 4.137-.834 5.646-2.348l33.682-33.673c3.12-3.12 3.12-8.187 0-11.311zm0-66.284c-3.129-3.129-8.192-3.129-11.321 0l-26.301 26.296-6.986-12.111c-2.213-3.823-7.102-5.135-10.935-2.927-3.819 2.208-5.13 7.102-2.926 10.93l12.208 21.137c1.239 2.155 3.419 3.607 5.882 3.929.347.048.699.072 1.051.072 2.107 0 4.137-.834 5.646-2.343l33.682-33.672c3.12-3.124 3.12-8.187 0-11.311zm140.12 221.35c0-4.421-3.583-7.999-7.999-7.999h-106.693c-4.416 0-7.999 3.578-7.999 7.999s3.582 7.999 7.999 7.999h106.693c4.416 0 7.999-3.578 7.999-7.999zm0-66.284c0-4.416-3.583-7.999-7.999-7.999h-106.693c-4.416 0-7.999 3.582-7.999 7.999s3.582 7.999 7.999 7.999h106.693c4.416 0 7.999-3.582 7.999-7.999zm0-66.29c0-4.416-3.583-7.999-7.999-7.999h-106.693c-4.416 0-7.999 3.582-7.999 7.999s3.582 8.004 7.999 8.004h106.693c4.416 0 7.999-3.582 7.999-8.004zm0-66.285c0-4.421-3.583-8.004-7.999-8.004h-106.693c-4.416 0-7.999 3.582-7.999 8.004s3.582 7.999 7.999 7.999h106.693c4.416 0 7.999-3.583 7.999-7.999zm-265.74-62.867c-4.421-.164-8.11 3.307-8.259 7.724l-.077 2.218c-19.522-25.322-50.032-40.78-82.813-40.78-57.611 0-104.48 46.864-104.48 104.476s46.869 104.475 104.48 104.475c21.368 0 41.922-6.412 59.429-18.543 17.101-11.841 30.163-28.297 37.771-47.568 1.62-4.113-.391-8.76-4.498-10.38-4.113-1.625-8.76.391-10.38 4.503-13.432 34.01-45.75 55.991-82.321 55.991-48.788 0-88.477-39.695-88.477-88.478s39.688-88.478 88.476-88.478c27.333 0 52.79 12.695 69.361 33.552l-3.331-1.74c-3.92-2.049-8.751-.53-10.79 3.385-2.049 3.915-.53 8.751 3.38 10.795l27.53 14.377c2.43 1.273 5.352 1.205 7.733-.178 2.367-1.384 3.867-3.891 3.958-6.639l1.037-30.442c.154-4.416-3.307-8.119-7.729-8.269zm-91.153 14.303c18.533 11.571 40.973 18.164 53.036 21.243v52.012c0 6.436-1.543 12.261-4.831 17.797-9.007 15.166-31.447 27.106-48.205 37.237-16.758-10.131-39.198-22.071-48.205-37.237-3.288-5.536-4.831-11.36-4.831-17.797v-52.012c12.063-3.079 34.503-9.672 53.036-21.243zm18.337 40.884-27.839 27.839-7.555-13.076c-2.208-3.828-7.097-5.135-10.925-2.931-3.833 2.213-5.14 7.102-2.931 10.93l12.757 22.106c1.254 2.155 3.423 3.606 5.892 3.929.352.048.699.067 1.042.067 2.107 0 4.146-.834 5.66-2.343l35.206-35.211c3.124-3.12 3.124-8.187 0-11.311-3.114-3.124-8.187-3.124-11.306 0zm.474 139.335v29.849h24.93v-29.849zm64.151 0h-23.479v37.72c0 4.351-3.523 7.875-7.872 7.875h-40.67c-4.349 0-7.873-3.525-7.873-7.875v-37.72h-23.478c-5.127 0-9.322 4.195-9.322 9.321v103.372c0 5.127 4.195 9.322 9.322 9.322h103.372c5.127 0 9.321-4.195 9.321-9.322v-103.372c0-5.127-4.195-9.321-9.321-9.321zm0 150.55h-23.479v37.72c0 4.351-3.523 7.875-7.872 7.875h-40.67c-4.349 0-7.873-3.525-7.873-7.875v-37.72h-23.478c-5.127 0-9.322 4.195-9.322 9.321v103.372c0 5.127 4.195 9.322 9.322 9.322h103.372c5.127 0 9.321-4.195 9.321-9.322v-103.372c0-5.126-4.195-9.321-9.321-9.321zm-64.151 0v29.85h24.93v-29.85zm150.55 0v29.85h24.93v-29.85zm64.151 0h-23.479v37.72c0 4.351-3.523 7.875-7.872 7.875h-40.67c-4.349 0-7.873-3.525-7.873-7.875v-37.72h-23.478c-5.127 0-9.322 4.195-9.322 9.321v103.372c0 5.127 4.195 9.322 9.322 9.322h103.372c5.127 0 9.321-4.195 9.321-9.322v-103.372c0-5.126-4.194-9.321-9.321-9.321zm150.55 0h-23.479v37.72c0 4.351-3.523 7.875-7.872 7.875h-40.671c-4.349 0-7.873-3.525-7.873-7.875v-37.72h-23.478c-5.127 0-9.322 4.195-9.322 9.321v103.372c0 5.127 4.195 9.322 9.322 9.322h103.372c5.127 0 9.321-4.195 9.321-9.322v-103.372c0-5.126-4.194-9.321-9.321-9.321zm-64.151 0v29.85h24.93v-29.85z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Descripci\u00f3n - Informaci\u00f3n detallada sobre el art\u00edculo, incluyendo especificaciones y uso.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" clip-rule=\"evenodd\" fill-rule=\"evenodd\" height=\"1.707in\" image-rendering=\"optimizeQuality\" shape-rendering=\"geometricPrecision\" text-rendering=\"geometricPrecision\" viewbox=\"0 0 1707 1707\" width=\"1.707in\"><g id=\"Layer_x0020_1\"><path d=\"m1600 1532h-1493c-59 0-107-48-107-107v-37h1707v37c0 59-48 107-107 107zm-1600-184v-218c0-59 48-107 107-107h43v231c0 11 9 20 20 20 12 0 20-9 20-20v-231h131v126c0 11 9 20 20 20s20-9 20-20v-126h131v231c0 11 9 20 20 20s20-9 20-20v-231h131v126c0 11 8 20 20 20 11 0 20-9 20-20v-126h130v231c0 11 9 20 20 20s20-9 20-20v-231h131v126c0 11 9 20 20 20s20-9 20-20v-126h131v231c0 11 9 20 20 20s20-9 20-20v-231h130v126c0 11 9 20 20 20s20-9 20-20v-126h131v231c0 11 9 20 20 20s20-9 20-20v-231h44c59 0 107 48 107 107v218z\"><\/path><path d=\"m853 933c-208 0-378-170-378-379s169-379 378-379 379 170 379 379-170 379-379 379zm0-94h-1-1c-3 0-5-1-8-2l-230-133c-6-4-10-10-10-17v-266c0-7 4-14 10-17l230-133c7-4 14-4 20 0l230 133h1 1v1s1 0 1 1c2 1 3 3 4 4l1 1v1c2 3 3 7 2 10v265c0 7-4 13-10 17l-230 133c-2 1-5 2-8 2h-1zm-210-164 190 110v-220l-190-109zm230 110 190-110v-219l-190 109zm170-364-190-110-190 110 190 110z\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unidad de medida (UM) - Define c\u00f3mo se mide el art\u00edculo (por ejemplo, kg, litro, tambor, pies, cada uno, pieza, etc.).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" height=\"512\" viewbox=\"0 0 512 512\" width=\"512\"><path clip-rule=\"evenodd\" d=\"m162.496 346.058h47.49l35.559 35.682v-17.719l-11.199-11.192h11.199v-60.409l-60.902-35.188-36.788 21.288v50.808h-106.421v-71.112h106.421v5.908l24.239-14.025-55.609-32.112v5.537h-106.299v-71.114h106.299v51.179l71.109 40.973.127.121 57.824 33.347v-62.011h-46.879v-63.978l-59.42-34.324h-93.87v-71.237h106.293v63.976l59.424 34.329h34.452v-67.547h-46.879v-71.237h106.301v71.237h-46.877v67.547h34.451l59.424-34.329v-63.976h106.298v71.234h-93.872l-59.425 34.324v63.978h-46.877v62.011l57.826-33.347.245-.121 79.359-45.768v-46.384h106.294v71.114h-106.293v-10.338l-63.977 36.913 24.359 14.025v-5.908h106.298v71.112h-106.298v-50.805l-36.785-21.288-61.027 35.188v91.044h83.05c8.12 0 14.763 6.643 14.763 14.764v93.134c0 8.121-6.643 14.639-14.763 14.639h-178.644c-8.12 0-14.642-6.518-14.642-14.639v-130.659c0-7.997 6.522-14.645 14.642-14.645zm70.129-177.529c-3.443 0-6.274-2.71-6.274-6.155 0-3.564 2.832-6.275 6.274-6.275h46.751c3.445 0 6.272 2.711 6.272 6.275 0 3.445-2.827 6.155-6.272 6.155zm-8.368 36.171c-3.442 0-6.149-2.833-6.149-6.277 0-3.443 2.707-6.274 6.149-6.274h24.609c3.44 0 6.271 2.831 6.271 6.274 0 3.444-2.831 6.277-6.271 6.277zm40.6 0c-3.444 0-6.148-2.833-6.148-6.277 0-3.443 2.704-6.274 6.148-6.274h14.519c3.445 0 6.272 2.831 6.272 6.274 0 3.444-2.827 6.277-6.272 6.277zm-40.6-18.086c-3.442 0-6.149-2.832-6.149-6.277 0-3.441 2.707-6.149 6.149-6.149h55.119c3.445 0 6.272 2.708 6.272 6.149 0 3.445-2.827 6.277-6.272 6.277zm-144.933-116.388c-3.44 0-6.271-2.705-6.271-6.151 0-3.445 2.831-6.273 6.271-6.273h46.757c3.445 0 6.273 2.828 6.273 6.273 0 3.446-2.828 6.151-6.273 6.151zm-8.363 36.17c-3.445 0-6.148-2.826-6.148-6.271 0-3.447 2.704-6.274 6.148-6.274h24.605c3.447 0 6.275 2.827 6.275 6.274 0 3.445-2.829 6.271-6.275 6.271zm40.601 0c-3.445 0-6.271-2.826-6.271-6.271 0-3.447 2.825-6.274 6.271-6.274h14.519c3.445 0 6.273 2.827 6.273 6.274 0 3.445-2.828 6.271-6.273 6.271zm-40.601-18.085c-3.445 0-6.148-2.704-6.148-6.273 0-3.445 2.704-6.151 6.148-6.151h55.12c3.445 0 6.273 2.706 6.273 6.151 0 3.569-2.828 6.273-6.273 6.273zm-26.82 87.841c-3.447 0-6.278-2.826-6.278-6.273 0-3.444 2.832-6.272 6.278-6.272h46.751c3.446 0 6.277 2.828 6.277 6.272 0 3.447-2.831 6.273-6.277 6.273zm-8.367 36.048c-3.446 0-6.15-2.703-6.15-6.147 0-3.447 2.704-6.274 6.15-6.274h24.605c3.449 0 6.278 2.827 6.278 6.274 0 3.444-2.829 6.147-6.278 6.147zm40.601 0c-3.442 0-6.272-2.703-6.272-6.147 0-3.447 2.831-6.274 6.272-6.274h14.518c3.446 0 6.277 2.827 6.277 6.274 0 3.444-2.831 6.147-6.277 6.147zm-40.601-17.961c-3.446 0-6.15-2.827-6.15-6.273 0-3.445 2.704-6.273 6.15-6.273h55.119c3.446 0 6.277 2.828 6.277 6.273 0 3.446-2.831 6.273-6.277 6.273zm39.618 87.721c-3.445 0-6.273-2.826-6.273-6.273 0-3.446 2.828-6.271 6.273-6.271h46.751c3.445 0 6.273 2.825 6.273 6.271 0 3.447-2.828 6.273-6.273 6.273zm-8.244 36.171c-3.447 0-6.278-2.827-6.278-6.271 0-3.447 2.831-6.274 6.278-6.274h24.486c3.565 0 6.272 2.827 6.272 6.274 0 3.443-2.707 6.271-6.272 6.271zm40.601 0c-3.446 0-6.272-2.827-6.272-6.271 0-3.447 2.826-6.274 6.272-6.274h14.394c3.445 0 6.273 2.827 6.273 6.274 0 3.443-2.828 6.271-6.273 6.271zm-40.601-18.083c-3.447 0-6.278-2.828-6.278-6.275 0-3.446 2.831-6.271 6.278-6.271h54.995c3.445 0 6.273 2.824 6.273 6.271s-2.828 6.275-6.273 6.275zm322.709-18.088c-3.441 0-6.273-2.826-6.273-6.273 0-3.446 2.832-6.271 6.273-6.271h46.751c3.447 0 6.279 2.825 6.279 6.271 0 3.447-2.832 6.273-6.279 6.273zm-8.366 36.171c-3.443 0-6.275-2.827-6.275-6.271 0-3.447 2.832-6.274 6.275-6.274h24.608c3.442 0 6.273 2.827 6.273 6.274 0 3.443-2.832 6.271-6.273 6.271zm40.603 0c-3.449 0-6.277-2.827-6.277-6.271 0-3.447 2.828-6.274 6.277-6.274h14.514c3.447 0 6.279 2.827 6.279 6.274 0 3.443-2.832 6.271-6.279 6.271zm-40.603-18.083c-3.443 0-6.275-2.828-6.275-6.275 0-3.446 2.832-6.271 6.275-6.271h55.117c3.447 0 6.279 2.824 6.279 6.271s-2.832 6.275-6.279 6.275zm47.984-123.896c-3.445 0-6.277-2.826-6.277-6.273 0-3.444 2.832-6.272 6.277-6.272h46.751c3.445 0 6.276 2.828 6.276 6.272 0 3.447-2.831 6.273-6.276 6.273zm-8.37 36.048c-3.445 0-6.275-2.703-6.275-6.147 0-3.447 2.831-6.274 6.275-6.274h24.605c3.446 0 6.279 2.827 6.279 6.274 0 3.444-2.833 6.147-6.279 6.147zm40.604 0c-3.446 0-6.273-2.703-6.273-6.147 0-3.447 2.827-6.274 6.273-6.274h14.517c3.445 0 6.276 2.827 6.276 6.274 0 3.444-2.831 6.147-6.276 6.147zm-40.604-17.961c-3.445 0-6.275-2.827-6.275-6.273 0-3.445 2.831-6.273 6.275-6.273h55.12c3.445 0 6.276 2.828 6.276 6.273 0 3.446-2.831 6.273-6.276 6.273zm-35.182-124.013c-3.45 0-6.277-2.705-6.277-6.151 0-3.445 2.827-6.273 6.277-6.273h46.751c3.443 0 6.274 2.828 6.274 6.273 0 3.446-2.832 6.151-6.274 6.151zm-8.367 36.17c-3.445 0-6.153-2.826-6.153-6.271 0-3.447 2.708-6.274 6.153-6.274h24.605c3.446 0 6.278 2.827 6.278 6.274 0 3.445-2.832 6.271-6.278 6.271zm40.598 0c-3.443 0-6.15-2.826-6.15-6.271 0-3.447 2.708-6.274 6.15-6.274h14.521c3.443 0 6.274 2.827 6.274 6.274 0 3.445-2.832 6.271-6.274 6.271zm-40.598-18.085c-3.445 0-6.153-2.704-6.153-6.273 0-3.445 2.708-6.151 6.153-6.151h55.119c3.443 0 6.274 2.706 6.274 6.151 0 3.569-2.832 6.273-6.274 6.273zm-144.931-58.438c-3.443 0-6.274-2.833-6.274-6.274 0-3.443 2.832-6.276 6.274-6.276h46.751c3.445 0 6.272 2.833 6.272 6.276 0 3.441-2.827 6.274-6.272 6.274zm-8.368 36.043c-3.442 0-6.149-2.703-6.149-6.149 0-3.569 2.707-6.271 6.149-6.271h24.609c3.44 0 6.271 2.701 6.271 6.271 0 3.446-2.831 6.149-6.271 6.149zm40.6 0c-3.444 0-6.148-2.703-6.148-6.149 0-3.569 2.704-6.271 6.148-6.271h14.519c3.445 0 6.272 2.701 6.272 6.271 0 3.446-2.827 6.149-6.272 6.149zm-40.6-18.085c-3.442 0-6.149-2.703-6.149-6.15 0-3.445 2.707-6.275 6.149-6.275h55.119c3.445 0 6.272 2.83 6.272 6.275 0 3.447-2.827 6.15-6.272 6.15zm46.387 304.997h61.019c8.12 0 14.765 6.642 14.765 14.641v4.061c-1.72-.371-3.445-.493-5.289-.493h-70.496v-18.209z\" fill-rule=\"evenodd\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Clasificaci\u00f3n - Asigna el art\u00edculo a una categor\u00eda pertinente (por ejemplo, materia prima, pieza de recambio, producto acabado).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9241685 e-flex e-con-boxed e-con e-parent\" data-id=\"9241685\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b869e elementor-widget elementor-widget-heading\" data-id=\"a7b869e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"item-categories\">Categor\u00edas de art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f2ae0a e-flex e-con-boxed e-con e-parent\" data-id=\"4f2ae0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba4e4ee elementor-widget elementor-widget-text-editor\" data-id=\"ba4e4ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los art\u00edculos se agrupan en categor\u00edas espec\u00edficas para simplificar su identificaci\u00f3n y gesti\u00f3n.<\/p><p>Las clasificaciones comunes incluyen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e0f4ea e-flex e-con-boxed e-con e-parent\" data-id=\"3e0f4ea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19819a6 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"19819a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" height=\"512\" viewbox=\"0 0 480.008 480.008\" width=\"512\"><g><path d=\"m253.505 408.242h-61.008c-4.01 0-6.829-3.967-5.482-7.745 13.907-38.992-1.938-81.966-35.739-103.504-4.932-3.143-2.771-10.751 3.077-10.751h137.288c5.846 0 8.01 7.607 3.08 10.749-33.873 21.581-49.579 64.644-35.735 103.507 1.347 3.777-1.471 7.744-5.481 7.744z\"><\/path><circle cx=\"104\" cy=\"371.242\" r=\"16\"><\/circle><path d=\"m104 299.242c-39.7 0-72 32.3-72 72s32.3 72 72 72 72-32.3 72-72-32.3-72-72-72zm0 104c-17.645 0-32-14.355-32-32s14.355-32 32-32 32 14.355 32 32-14.355 32-32 32z\"><\/path><circle cx=\"342\" cy=\"371.242\" r=\"16\"><\/circle><path d=\"m342 299.242c-39.7 0-72 32.3-72 72s32.3 72 72 72 72-32.3 72-72-32.3-72-72-72zm0 104c-17.645 0-32-14.355-32-32s14.355-32 32-32 32 14.355 32 32-14.355 32-32 32z\"><\/path><path d=\"m56.822 296.984c-12.463 7.945-22.792 18.94-29.941 31.91-2.864 5.196-10.864 3.144-10.881-2.789 0-.077 0-34.128 0-34.128 0-3.294 2.724-5.925 6.015-5.815 4.126.138 12.243.119 31.679.098 5.829-.008 8.043 7.591 3.128 10.724z\"><\/path><path d=\"m423.951 286.152c3.303-.123 6.049 2.508 6.049 5.814v34.139c-.016 5.934-8.017 7.986-10.881 2.789-7.147-12.966-17.472-23.961-29.937-31.907-4.915-3.133-2.698-10.732 3.13-10.725 19.312.024 27.398.047 31.639-.11z\"><\/path><path d=\"m277 82.242v13c0 4.418-3.582 8-8 8-13.006 0-18.318-.538-26.241 2.251-5.193 1.828-7.216-2.251-18.759-2.251h-106c-4.418 0-8-3.582-8-8v-13c0-13.255 10.745-24 24-24h119c13.255 0 24 10.745 24 24z\"><\/path><path d=\"m308.267 129.433-34.253 33.141c-3.726 3.605-10.041.993-10.053-4.254-.031-13.657 1.067-20.901-3.18-30.804-1.68-3.917 1.176-8.274 5.439-8.274h37.924c5.33 0 7.954 6.485 4.123 10.191z\"><\/path><path d=\"m470.28 51.802-4.38-4.52c-13.25-13.7-35.18-14.06-48.88-.81l-140.69 136.12c-14.94 14.46-15.34 38.381-.88 53.33 14.494 14.97 38.338 15.386 53.33.88l140.69-136.119c13.695-13.264 14.123-35.132.81-48.881zm-157.623 160.097c-1.506 1.507-3.186 3.343-6.657 3.343-7.065 0-10.711-8.602-5.657-13.657l1-1c3.125-3.123 8.189-3.123 11.314 0 3.124 3.125 3.124 8.19 0 11.314z\"><\/path><path d=\"m248 143.242v13c0 4.418-3.582 8-8 8h-192c-4.418 0-8-3.582-8-8v-13c0-13.255 10.745-24 24-24h160c13.255 0 24 10.745 24 24z\"><\/path><path d=\"m446 204.242v42c0 13.255-10.745 24-24 24h-398c-13.255 0-24-10.745-24-24v-42c0-13.255 10.745-24 24-24h220.7c5.527 0 9.457 5.496 7.535 10.677-13.007 35.056 12.612 71.857 49.435 72.483 9.906.322 21.267-2.619 30.92-9.16 5.516-3.721 2.196-.997 75.334-71.75 1.492-1.443 3.486-2.25 5.562-2.25h8.514c13.255 0 24 10.745 24 24z\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Materias primas - Se utilizan en los procesos de producci\u00f3n (por ejemplo, metales, pl\u00e1sticos, productos qu\u00edmicos).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7943fab e-flex e-con-boxed e-con e-parent\" data-id=\"7943fab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8422089 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8422089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" height=\"512\" viewbox=\"0 0 68 68\" width=\"512\"><g><g><path d=\"m32.1 30.9v6.5c0 .4-.1.8-.4 1.1l-1.7 2c-.3.4-.8.6-1.3.6s-1-.2-1.3-.6l-.4-.6-.5.7c-.3.4-.8.6-1.3.6s-1-.2-1.3-.6l-.5-.6-.5.6c-.3.4-.8.6-1.3.6s-1-.2-1.3-.6l-1.6-2c-.2-.3-.4-.7-.4-1.1v-6.5h-15.8v29.9c0 1.2 1 2.1 2.1 2.1h30.6c-.2-.4-.3-.9-.3-1.4v-20.4c0-.6.2-1.2.6-1.7l.1-.1 4.9-5.7c.5-.7 1.4-1.1 2.3-1.1h5.1v-1.7zm-13.1 26.7c0 .3-.3.5-.5.5h-10.3c-.3 0-.6-.2-.6-.5v-5.2c0-.3.3-.5.6-.5h10.3c.3 0 .5.2.5.5z\"><\/path><path d=\"m12.3 17.6h5.9v11.9h-15.5c.1-.2.2-.4.3-.5l7.7-10.5c.3-.6.9-.9 1.6-.9z\"><\/path><path d=\"m47.7 29.4h-15.6v-11.8h1.9c1.3 4.8 5.6 8.3 10.8 8.3h.3c1.1 1.3 2.4 3.2 2.6 3.5z\"><\/path><path d=\"m30.6 17.6v19.9.1l-1.6 2c-.1.1-.2.1-.3 0l-1.6-1.9c-.1-.1-.2-.1-.3 0l-1.6 1.9c-.1.1-.2.1-.3 0l-1.6-1.9c-.1-.1-.2-.1-.3 0l-1.6 1.9c-.1.1-.2.1-.3 0l-1.7-2v-.1-19.9z\"><\/path><\/g><g><path d=\"m55.9 42.3v3.6c0 .4-.1.8-.4 1.1l-.9 1.1c-.3.4-.8.6-1.4.6-.4 0-.8-.2-1.2-.4-.3.3-.7.4-1.2.4-.4 0-.8-.2-1.2-.4-.3.3-.7.4-1.2.4s-1-.2-1.4-.6l-.6-1.1c-.3-.3-.4-.7-.4-1.1v-3.6h-9.5v19.4c0 .8.6 1.4 1.4 1.4h26.3c.8 0 1.4-.6 1.4-1.4v-19.4zm-8.9 17.2c0 .2-.2.4-.3.4h-6.7c-.2 0-.4-.2-.4-.4v-3.3c0-.2.2-.3.4-.3h6.6c.2 0 .3.1.3.3v3.3z\"><\/path><path d=\"m42.7 34.2h3.3v6.6h-9.4c0-.1.1-.2.2-.3l4.9-5.7c.2-.4.6-.6 1-.6z\"><\/path><path d=\"m65.4 40.8h-9.4v-6.6h3.2c.4 0 .8.2 1.1.6l4.9 5.7c.1 0 .1.1.2.3z\"><\/path><path d=\"m54.4 34.2v11.7c0 .1 0 .1-.1.2l-.9 1.1c-.1.1-.3.1-.4 0l-.8-.9c-.1-.1-.3-.1-.4 0l-.8.9c-.1.1-.3.1-.4 0l-.6-1c-.1-.1-.3-.1-.4 0l-.8.9c-.1.1-.3.1-.4 0l-.9-1.1s-.1-.1-.1-.2v-11.6z\"><\/path><\/g><g><path d=\"m44.8 9.2c-3 0-5.4 2.4-5.4 5.4s2.4 5.4 5.4 5.4 5.4-2.4 5.4-5.4c.1-3-2.4-5.4-5.4-5.4zm2.4 5-2.8 2.1c-.2.1-.4.2-.6.1-.2 0-.4-.1-.5-.3l-1.1-1.5c-.2-.3-.2-.8.2-1 .3-.2.8-.2 1.1.2l.6.9 2.2-1.7c.3-.3.8-.2 1.1.2.2.3.2.8-.2 1z\"><\/path><path d=\"m44.8 5c-5.4 0-9.7 4.3-9.7 9.7 0 5.3 4.3 9.7 9.7 9.7 5.3 0 9.7-4.3 9.7-9.7s-4.3-9.7-9.7-9.7zm0 16.5c-3.8 0-6.9-3.1-6.9-6.9s3.1-6.9 6.9-6.9 6.9 3.1 6.9 6.9c.1 3.8-3 6.9-6.9 6.9z\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Productos acabados - Productos finales listos para su venta o distribuci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6814c39 e-flex e-con-boxed e-con e-parent\" data-id=\"6814c39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-125a22f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"125a22f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewbox=\"0 0 48 48\"><path d=\"m27.39 8.21-.67 1.32c-.15.28-.22.59-.22.91v10.56h-3v-10.56c0-.32-.07-.63-.22-.91l-.67-1.32c-.39-.77-.43-1.67-.11-2.47l1.25-3.11c.15-.38.52-.63.93-.63h.64c.41 0 .78.25.93.63l1.25 3.11c.32.8.28 1.7-.11 2.47z\"><\/path><path d=\"m16.36 21h-4.05l-1.04-5.88h.02c.15 0 .31-.02.47-.04l2.96-.53c.17-.03.33-.07.48-.13z\"><\/path><path d=\"m17.526 4.012-.84.148c-.217.038-.458.239-.552.438-.251.529-.745.933-1.366 1.043-.64.113-1.26-.114-1.678-.55-.16-.167-.404-.225-.632-.185l-1.948.343c-1.987.35-3.834 1.453-5.079 3.241-1.189 1.69-1.616 3.684-1.358 5.576.06.44.658.57.899.197.874-1.349 2.286-2.348 3.994-2.649l.645-.114c.408-.072.797.2.869.608l.069.389c.072.408.461.68.869.608l2.954-.521c.408-.072.68-.461.608-.869l-.263-1.491c-.063-.36.138-.725.485-.838.07-.023.141-.041.216-.054.622-.11 1.225.102 1.642.514.156.154.45.26.665.222l.751-.132c.501-.088.772-.477.7-.885l-.781-4.432c-.072-.408-.461-.68-.869-.608z\"><\/path><path d=\"m43.79 10.95c-.52 1.96-1.95 3.42-3.72 4.07-.32.12-.57.37-.66.69l-1.42 5.29h-6.21l1.83-6.82c.09-.33-.01-.67-.22-.93-.94-1.12-1.46-2.56-1.39-4.04.12-2.72 1.88-4.77 4.13-5.51.38-.12.75.23.64.62l-.86 3.21c-.09.34.01.7.25.95l1.22 1.26c.25.27.63.37.99.27l1.68-.48c.34-.1.6-.37.69-.71l.86-3.21c.11-.38.6-.51.86-.21 1.31 1.46 1.88 3.52 1.33 5.55z\"><\/path><path d=\"m44 30v10c0 3.31-2.69 6-6 6h-28c-3.31 0-6-2.69-6-6v-10h5.77c.54.62 1.34 1 2.23 1h2c.89 0 1.69-.38 2.23-1h15.54c.54.62 1.34 1 2.23 1h2c.89 0 1.69-.38 2.23-1z\"><\/path><path d=\"m4 23h5v5h-5c-.55 0-1-.45-1-1v-3c0-.55.45-1 1-1z\"><\/path><path d=\"m17 23h14v5h-14z\"><\/path><path d=\"m45 24v3c0 .55-.45 1-1 1h-5v-5h5c.55 0 1 .45 1 1z\"><\/path><path d=\"m14 29h-2c-.552 0-1-.448-1-1v-5h4v5c0 .552-.448 1-1 1z\"><\/path><path d=\"m36 29h-2c-.552 0-1-.448-1-1v-5h4v5c0 .552-.448 1-1 1z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Piezas de recambio - Componentes de repuesto para maquinaria o equipos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-333a899 e-flex e-con-boxed e-con e-parent\" data-id=\"333a899\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f82db8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8f82db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 64 64\" width=\"512\" height=\"512\"><g id=\"Layer_2\" data-name=\"Layer 2\"><path d=\"M58.17,40.99a.9711.9711,0,0,0-1.1.63c-.01.03-1.3,2.54-10.01,2.54a26.2284,26.2284,0,0,0-3.26.22L44.96,19H47a3.0088,3.0088,0,0,0,3-3V14a3.0024,3.0024,0,0,0-3-3H45V6.56a5.5623,5.5623,0,0,0-6.65-5.45L10.41,6.7A2.9777,2.9777,0,0,0,8.47,8.05,3.9832,3.9832,0,0,0,8,15.86V16a3.0088,3.0088,0,0,0,3,3V51.09A5.9967,5.9967,0,0,0,12,63H33.16a64.498,64.498,0,0,0,11.29-.68,17.4834,17.4834,0,0,0,9.58-4.56c3.39-3.41,5.02-8.57,4.97-15.77A1.0182,1.0182,0,0,0,58.17,40.99ZM7,12a2,2,0,1,1,2,2A2.0059,2.0059,0,0,1,7,12Zm3,4v-.14A4.0167,4.0167,0,0,0,12.86,13H47a1.0029,1.0029,0,0,1,1,1v2a1.0029,1.0029,0,0,1-1,1H11A1.0029,1.0029,0,0,1,10,16Zm2,45a4,4,0,1,1,4-4A3.9989,3.9989,0,0,1,12,61ZM23.94,44H21.93a4.8741,4.8741,0,0,1-4.25-2.51,5.2208,5.2208,0,0,1,.05-5.24l1.17-1.97-.45.15a1.0024,1.0024,0,1,1-.64-1.9l3.01-1a.9961.9961,0,0,1,1.3.78l.5,3a.9991.9991,0,0,1-.82,1.16c-.05,0-.11.01-.16.01a1.0075,1.0075,0,0,1-.99-.83l-.05-.31-1.15,1.93a3.1683,3.1683,0,0,0-.03,3.23A2.8673,2.8673,0,0,0,21.93,42h2.01a1,1,0,0,1,0,2Zm1.35-16.55-1.64,2.76a1,1,0,1,1-1.72-1.02l1.64-2.76A4.8984,4.8984,0,0,1,27.7,24a4.8292,4.8292,0,0,1,4.19,2.28l2.18,3.41.07-.45a1.0037,1.0037,0,0,1,1.98.33l-.51,3a.9975.9975,0,0,1-.47.69.9463.9463,0,0,1-.51.15.8662.8662,0,0,1-.32-.06l-3-1a.9961.9961,0,1,1,.63-1.89l.31.1-2.05-3.2A2.8418,2.8418,0,0,0,27.78,26h-.05A2.881,2.881,0,0,0,25.29,27.45Zm4.73,18.23a.9855.9855,0,0,1-.73.32,1.0141,1.0141,0,0,1-.68-.26l-2.18-2.01a1.0024,1.0024,0,0,1-.03-1.44l2.12-2.12a1.0079,1.0079,0,0,1,1.42,0,.9959.9959,0,0,1,0,1.41l-.42.42h4.55a2.8857,2.8857,0,0,0,2.53-1.54,3.1473,3.1473,0,0,0-.11-3.28l-.91-1.43a.9986.9986,0,0,1,1.68-1.08l.92,1.43a5.2294,5.2294,0,0,1,.18,5.32A4.865,4.865,0,0,1,34.07,44H29.68l.28.26A1,1,0,0,1,30.02,45.68Zm22.6,10.67C48.37,60.63,41.5,60.97,34.63,61a20.5369,20.5369,0,0,1,5.13-4.87,6.8014,6.8014,0,0,0,4.37,1.53,7.4156,7.4156,0,0,0,3.32-.77.9973.9973,0,1,0-.9-1.78,5.3761,5.3761,0,0,1-4.97-.16,44.5138,44.5138,0,0,1,8.71-3.99,1.0028,1.0028,0,1,0-.58-1.92c-.16.05-1.38.43-3.11,1.15a7.4352,7.4352,0,0,1,1.11-1.48,1.0041,1.0041,0,0,0-1.42-1.42,8.4608,8.4608,0,0,0-2.22,4.03,37.3221,37.3221,0,0,0-6.71,4.08,5.8189,5.8189,0,0,1,1.32-3.67.9979.9979,0,0,0-1.35-1.47c-.1.09-2.36,2.22-1.95,6.84a20.9147,20.9147,0,0,0-2.13,2.39c-.61-3.36-.09-6.27,1.56-8.5,2.29-3.12,6.64-4.83,12.25-4.83,5.3,0,8.25-.89,9.89-1.82C56.67,49.76,55.25,53.7,52.62,56.35Z\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Consumibles - Art\u00edculos utilizados en las operaciones diarias (por ejemplo, lubricantes, elementos de fijaci\u00f3n, equipos de seguridad).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c1b1a0 e-flex e-con-boxed e-con e-parent\" data-id=\"1c1b1a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c1628 elementor-widget elementor-widget-text-editor\" data-id=\"c1c1628\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La categorizaci\u00f3n mejora la capacidad de b\u00fasqueda, la elaboraci\u00f3n de informes y la eficacia de la gesti\u00f3n de existencias.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6aefcc e-flex e-con-boxed e-con e-parent\" data-id=\"c6aefcc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ad9d5a elementor-widget elementor-widget-heading\" data-id=\"0ad9d5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"inventory-data-tab-and-stock-levels\">Ficha Datos de inventario y niveles de existencias<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e14370a e-flex e-con-boxed e-con e-parent\" data-id=\"e14370a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f53448 elementor-widget elementor-widget-text-editor\" data-id=\"1f53448\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los datos relacionados con el inventario son cruciales para el seguimiento de los movimientos de existencias y las estrategias de reposici\u00f3n. <a href=\"https:\/\/www.verdantis.com\/inventory-data-management\/\">Obtenga m\u00e1s informaci\u00f3n sobre pr\u00e1cticas eficaces de gesti\u00f3n de inventarios aqu\u00ed.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9bb6f22 e-flex e-con-boxed e-con e-parent\" data-id=\"9bb6f22\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9263f95 e-con-full e-flex e-con e-child\" data-id=\"9263f95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-57bd841 e-con-full pointer e-flex e-con e-child\" data-id=\"57bd841\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6220ac elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a6220ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" viewbox=\"0 0 512 512\" data-name=\"Layer 1\"><path d=\"m254.625 220.496c-13.89 3.855-40.621 12.019-44.674 28.743l-.283 43.767h-185.726v-64.233c0-42.18 34.753-68.797 78.605-79.824 13.748 10.006 30.699 15.931 49.039 15.931s35.263-5.924 49.04-15.931c38.92 9.808 70.668 31.89 77.301 66.246-7.965 1.474-15.789 3.203-23.301 5.301zm-103.04-67.606c39.345 0 71.433-32.088 71.433-71.433s-32.087-71.433-71.432-71.433-71.433 32.088-71.433 71.433 32.088 71.433 71.433 71.433zm106.243 79.172c-22.479 6.236-36.397 13.918-36.397 21.543s13.918 15.335 36.397 21.572c24.69 6.86 58.961 11.083 96.917 11.083s72.227-4.224 96.917-11.083c22.479-6.236 36.397-13.918 36.397-21.572s-13.918-15.307-36.397-21.543c-24.69-6.86-58.932-11.083-96.917-11.083s-72.227 4.224-96.917 11.083zm96.917 210.019c-38.976 0-74.353-4.422-100.091-11.565-14.06-3.884-25.398-8.788-33.222-14.4v53.206c0 7.654 13.918 15.335 36.397 21.572 24.69 6.832 58.961 11.083 96.917 11.083s72.227-4.252 96.917-11.083c22.479-6.236 36.397-13.918 36.397-21.572v-53.206c-7.824 5.613-19.162 10.517-33.222 14.4-25.71 7.143-61.115 11.565-100.091 11.565zm0-71.915c-38.976 0-74.353-4.422-100.091-11.565-14.06-3.883-25.398-8.759-33.222-14.4v53.234c0 7.625 13.918 15.307 36.397 21.543 24.69 6.86 58.961 11.083 96.917 11.083s72.227-4.224 96.917-11.083c22.479-6.236 36.397-13.918 36.397-21.543v-53.234c-7.824 5.641-19.162 10.517-33.222 14.4-25.71 7.143-61.115 11.565-100.091 11.565zm0-71.915c-38.976 0-74.353-4.394-100.091-11.537-14.06-3.912-25.398-8.787-33.222-14.4v53.206c0 7.654 13.918 15.335 36.397 21.572 24.69 6.832 58.961 11.083 96.917 11.083s72.227-4.252 96.917-11.083c22.479-6.236 36.397-13.918 36.397-21.572v-53.206c-7.824 5.613-19.162 10.488-33.222 14.4-25.71 7.144-61.115 11.537-100.091 11.537zm-166.167 92.523v18.68c0 2.948-1.899 5.442-4.762 6.208l-11.735 3.146c-1.417 5.045-3.43 9.978-6.038 14.655l6.066 10.488c1.474 2.551 1.049 5.698-1.021 7.767l-13.209 13.209c-2.098 2.098-5.216 2.494-7.767 1.021l-10.517-6.066c-4.677 2.608-9.581 4.621-14.627 6.066l-3.146 11.735c-.765 2.834-3.26 4.762-6.208 4.762h-18.68c-2.976 0-5.471-1.928-6.236-4.762l-3.118-11.735c-5.046-1.417-9.978-3.458-14.655-6.066l-10.516 6.066c-2.551 1.474-5.669 1.077-7.739-1.021l-13.209-13.209c-2.098-2.098-2.494-5.216-1.02-7.767l6.066-10.488c-2.636-4.677-4.649-9.61-6.066-14.655l-11.736-3.146c-2.835-.766-4.762-3.26-4.762-6.208v-18.68c0-2.948 1.927-5.443 4.762-6.208l11.736-3.146c1.417-5.046 3.43-9.95 6.066-14.627l-6.066-10.517c-1.474-2.551-1.077-5.669 1.02-7.767l13.209-13.209c2.069-2.069 5.188-2.495 7.739-1.021l10.516 6.066c4.677-2.608 9.61-4.62 14.655-6.066l3.118-11.707c.765-2.863 3.26-4.762 6.236-4.762h18.68c2.948 0 5.442 1.899 6.208 4.762l3.146 11.707c5.046 1.446 9.949 3.458 14.627 6.066l10.517-6.066c2.551-1.474 5.669-1.049 7.767 1.021l13.209 13.209c2.069 2.098 2.495 5.216 1.021 7.767l-6.066 10.517c2.608 4.677 4.621 9.581 6.038 14.627l11.735 3.146c2.863.765 4.762 3.26 4.762 6.208zm-40.507 9.354c0-23.102-18.709-41.811-41.811-41.811s-41.811 18.709-41.811 41.811 18.737 41.782 41.811 41.782 41.811-18.708 41.811-41.782zm-41.811-29.821c-16.469 0-29.792 13.351-29.792 29.821s13.323 29.792 29.792 29.792 29.821-13.323 29.821-29.792-13.351-29.821-29.821-29.821zm166.167-268.611v-18.681c0-2.976 1.927-5.471 4.762-6.208l11.735-3.146c1.417-5.046 3.43-9.978 6.066-14.655l-6.066-10.517c-1.502-2.551-1.077-5.669 1.021-7.739l13.209-13.209c2.069-2.098 5.188-2.494 7.739-1.021l10.517 6.066c4.677-2.608 9.581-4.649 14.655-6.066l3.118-11.735c.765-2.835 3.26-4.762 6.236-4.762h18.68c2.948 0 5.443 1.927 6.208 4.762l3.118 11.735c5.074 1.417 9.978 3.43 14.655 6.066l10.517-6.066c2.551-1.474 5.669-1.077 7.739 1.021l13.209 13.209c2.098 2.069 2.523 5.187 1.049 7.739l-6.066 10.517c2.608 4.677 4.62 9.609 6.038 14.655l11.735 3.118c2.863.765 4.762 3.26 4.762 6.236v18.681c0 2.948-1.899 5.442-4.762 6.208l-11.735 3.146c-1.417 5.046-3.43 9.95-6.038 14.627l6.066 10.517c1.474 2.551 1.049 5.669-1.049 7.767l-13.209 13.209c-2.069 2.069-5.188 2.494-7.739 1.02l-10.517-6.066c-4.677 2.608-9.581 4.621-14.655 6.038l-3.118 11.736c-.765 2.863-3.26 4.762-6.208 4.762h-18.68c-2.976 0-5.471-1.899-6.236-4.762l-3.118-11.736c-5.074-1.417-9.978-3.43-14.655-6.038l-10.517 6.066c-2.551 1.474-5.669 1.049-7.739-1.02l-13.209-13.209c-2.098-2.098-2.523-5.216-1.021-7.767l6.066-10.517c-2.636-4.677-4.649-9.581-6.066-14.627l-11.735-3.146c-2.835-.765-4.762-3.26-4.762-6.208zm40.507-9.354c0 23.102 18.737 41.811 41.811 41.811s41.811-18.709 41.811-41.811-18.709-41.811-41.811-41.811-41.811 18.737-41.811 41.811zm41.811 29.82c16.469 0 29.821-13.351 29.821-29.82s-13.351-29.792-29.821-29.792-29.792 13.323-29.792 29.792 13.323 29.82 29.792 29.82z\" fill-rule=\"evenodd\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDatos de inventario\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abbabab elementor-widget elementor-widget-text-editor\" data-id=\"abbabab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Atributos relacionados con la gesti\u00f3n de existencias:<\/p><ul><li style=\"text-align: left;\"><p><strong>Niveles de existencias<\/strong> - La cantidad actual disponible en el inventario.<\/p><\/li><li style=\"text-align: left;\"><p><strong>Puntos de pedido<\/strong> - Nivel m\u00ednimo de existencias antes de que sea necesario reponerlas.<\/p><\/li><li style=\"text-align: left;\"><p><strong>Plazos de entrega<\/strong> - Tiempo estimado necesario para adquirir o fabricar el art\u00edculo.<\/p><\/li><li><p style=\"text-align: left;\"><strong>Stock de seguridad<\/strong> - Se mantiene la cantidad extra para evitar que se agoten las existencias.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b36a9d7 e-con-full pointer e-flex e-con e-child\" data-id=\"b36a9d7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-156cfc1 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"156cfc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" height=\"512\" viewbox=\"0 0 512 512\" width=\"512\"><path clip-rule=\"evenodd\" d=\"m190.23 75.85h131.54c4.406 0 8 3.594 8 8v329.388c-9.461-7.104-19.966-12.869-31.221-17.029 16.712-12.801 27.493-32.957 27.493-55.635 0-29.257-17.941-54.321-43.42-64.799h18.307v-36.929h-36.929v32.144c-5.332-.606-10.668-.607-16 0v-32.144h-36.929v36.929h18.309c-25.478 10.479-43.42 35.542-43.42 64.799 0 22.677 10.781 42.833 27.493 55.634-11.256 4.159-21.761 9.924-31.222 17.029v-329.387c-.001-4.406 3.593-8 7.999-8zm-165.54 354.868v-273.404c0-4.406 3.594-8 8-8h133.541v278.267c-3.298 3.522-6.392 7.24-9.262 11.136h-124.28c-4.406.001-7.999-3.593-7.999-7.999zm25.841-66.607v34.264h36.929v-34.264zm52.929 0v34.264h36.929v-34.264zm36.929-16v-34.264h-36.929v34.264zm-52.929 0v-34.264h-36.929v34.264zm52.929-50.263v-34.264h-36.929v34.264zm-52.929 0v-34.264h-36.929v34.264zm49.182-112.443h-82.364c-4.4 0-8 3.6-8 8v20.115c0 4.4 3.599 8 8 8h82.364c4.4 0 8-3.6 8-8v-20.115c0-4.4-3.6-8-8-8zm350.668 253.313v-289.403h-141.541v278.267c3.298 3.522 6.392 7.24 9.263 11.136zm-25.841-74.607v34.264h-36.929v-34.264zm-52.929 0v34.264h-36.929v-34.264zm-36.929-16v-34.264h36.929v34.264zm52.929 0v-34.264h36.929v34.264zm-52.929-50.263v-34.264h36.929v34.264zm52.929 0v-34.264h36.929v34.264zm-49.182-112.443h82.363c4.4 0 8 3.6 8 8v20.115c0 4.4-3.599 8-8 8h-82.363c-4.4 0-8-3.6-8-8v-20.115c0-4.4 3.6-8 8-8zm-119.357 101.129c-29.846 0-54.041 24.195-54.041 54.041s24.195 54.041 54.041 54.041 54.041-24.195 54.041-54.041-24.195-54.041-54.041-54.041zm-96.958 213.466 193.915-.001c5.076 0 8.841-4.592 7.846-9.569-9.785-48.939-52.987-85.814-104.803-85.814-51.818 0-95.019 36.876-104.804 85.815-.996 4.978 2.77 9.569 7.846 9.569zm60.386-459.011h28.571v-20.989c0-4.418 3.582-8 8-8s8 3.582 8 8v20.989h28.571c4.406 0 8 3.594 8 8v10.861h-89.142v-10.862c0-4.406 3.593-7.999 8-7.999zm-8.358 181.858h36.929v-36.929h-36.929zm52.929 0h36.929v-36.929h-36.929zm-44.93-112.562c-4.4 0-8 3.6-8 8v16.992c0 4.4 3.6 8 8 8h73.858c4.4 0 8-3.6 8-8v-16.992c0-4.4-3.6-8-8-8z\" fill-rule=\"evenodd\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tNiveles de existencias y jerarqu\u00eda\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-735d09a elementor-widget elementor-widget-text-editor\" data-id=\"735d09a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">El inventario se estructura en varios niveles para un mejor seguimiento:<\/p><ul><li style=\"text-align: left;\"><p><strong>Nivel de almac\u00e9n<\/strong> - Identifica el lugar de almacenamiento (por ejemplo, almac\u00e9n principal, dep\u00f3sito regional).<\/p><\/li><li style=\"text-align: left;\"><p><strong>Nivel de la papelera\/estanter\u00eda<\/strong> - Especifica la posici\u00f3n exacta de almacenamiento dentro de un almac\u00e9n.<\/p><\/li><li><p style=\"text-align: left;\"><strong>Seguimiento de lotes<\/strong> - Ayuda en el control de calidad y el seguimiento de la caducidad (para productos perecederos).<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89d7b2a e-flex e-con-boxed e-con e-parent\" data-id=\"89d7b2a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88d5558 elementor-widget elementor-widget-heading\" data-id=\"88d5558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"item-properties\">Propiedades de los art\u00edculos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33b65d0 e-flex e-con-boxed e-con e-parent\" data-id=\"33b65d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca0ec98 elementor-widget elementor-widget-text-editor\" data-id=\"ca0ec98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cada art\u00edculo tiene especificaciones detalladas que definen sus atributos f\u00edsicos y relacionados con la contrataci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92a2c9f e-flex e-con-boxed e-con e-parent\" data-id=\"92a2c9f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf58b3c elementor-widget elementor-widget-n-accordion\" data-id=\"bf58b3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Acorde\u00f3n. Abra los enlaces con Intro o Espacio, ci\u00e9rrelos con Escape y navegue con las teclas de flecha.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2000\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-2000\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Especificaciones <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2000\" class=\"elementor-element elementor-element-5f3e423 e-con-full e-flex e-con e-child\" data-id=\"5f3e423\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf96985 elementor-widget elementor-widget-text-editor\" data-id=\"cf96985\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Incluye detalles precisos del producto, como:<\/p><ul><li><p>Tipo, tama\u00f1o, dimensiones<\/p><\/li><li><p>Composici\u00f3n del material<\/p><\/li><li><p>Color y forma<\/p><\/li><li><p>Caracter\u00edsticas de rendimiento<\/p><\/li><li><p>Detalles de la solicitud<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2001\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2001\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Informaci\u00f3n sobre proveedores y precios <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2001\" class=\"elementor-element elementor-element-3487cea e-con-full e-flex e-con e-child\" data-id=\"3487cea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fa8d7b3 elementor-widget elementor-widget-text-editor\" data-id=\"fa8d7b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Captura los detalles relacionados con el proveedor:<\/p><ul><li><p><strong>Proveedor preferente<\/strong> - El vendedor principal que suministra el art\u00edculo.<\/p><\/li><li><p><strong>Proveedores alternativos<\/strong> - Proveedores de reserva en caso de indisponibilidad de existencias.<\/p><\/li><li><p><strong>Precios contractuales<\/strong> - Precio acordado para compras al por mayor.<\/p><\/li><li><p><strong>Descuentos y condiciones de pago<\/strong> - Negociaci\u00f3n de precios y calendarios de pago.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2002\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2002\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Informaci\u00f3n de estado <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2002\" class=\"elementor-element elementor-element-ee220ae e-con-full e-flex e-con e-child\" data-id=\"ee220ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47222da elementor-widget elementor-widget-text-editor\" data-id=\"47222da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Define el estado actual del elemento:<\/p><ul><li><p><strong>Activo<\/strong> - Art\u00edculo en uso regular.<\/p><\/li><li><p><strong>Obsoleto<\/strong> - El art\u00edculo ya no se fabrica ni se utiliza.<\/p><\/li><li><p><strong>En revisi\u00f3n<\/strong> - Se est\u00e1 evaluando la posibilidad de modificar o suprimir el art\u00edculo.<\/p><\/li><li><p><strong>Pendiente de aprobaci\u00f3n<\/strong> - El art\u00edculo est\u00e1 pendiente de autorizaci\u00f3n antes de su inclusi\u00f3n en la base de datos maestra.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20cb4e0 e-flex e-con-boxed e-con e-parent\" data-id=\"20cb4e0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-201e1e4 elementor-widget elementor-widget-image\" data-id=\"201e1e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Properties.png\" class=\"attachment-large size-large wp-image-28489\" alt=\"Una imagen que muestra diferentes propiedades de los datos maestros de un art\u00edculo\" srcset=\"https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Properties.png 1024w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Properties-300x225.png 300w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Properties-768x576.png 768w, https:\/\/www.verdantis.com\/wp-content\/uploads\/2025\/03\/Item-Properties-150x113.png 150w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0228fd e-flex e-con-boxed e-con e-parent\" data-id=\"c0228fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3722162 elementor-widget elementor-widget-heading\" data-id=\"3722162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\" id=\"why-are-these-attributes-important\">\u00bfPor qu\u00e9 son importantes estos atributos?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f352a6 e-flex e-con-boxed e-con e-parent\" data-id=\"0f352a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cb977d elementor-widget elementor-widget-text-editor\" data-id=\"5cb977d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Gesti\u00f3n precisa de los datos:<\/strong> Evita duplicaciones e incoherencias.<\/p><\/li><li><p><strong>Mejores decisiones de contrataci\u00f3n:<\/strong> Garantiza que se utilicen los proveedores y precios adecuados.<\/p><\/li><li><p><strong>Mejor control del inventario:<\/strong> Evita la falta o el exceso de existencias.<\/p><\/li><li><p><strong>Normalizaci\u00f3n:<\/strong> Mejora la compatibilidad entre las distintas unidades de negocio (compras, cadena de suministro, finanzas, etc.).<\/p><\/li><li><p><strong>Cumplimiento y auditor\u00eda:<\/strong> Garantiza el cumplimiento de los reglamentos y normas del sector.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8395609 e-flex e-con-boxed e-con e-parent\" data-id=\"8395609\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-616712f elementor-widget elementor-widget-text-editor\" data-id=\"616712f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Disponer de datos maestros de art\u00edculos bien estructurados con atributos claros permite a las organizaciones agilizar las operaciones, mejorar la toma de decisiones y garantizar la integridad de los datos. Estos atributos act\u00faan como la \u00fanica fuente de verdad, proporcionando un conjunto de datos coherente y fiable para el aprovisionamiento, la gesti\u00f3n de inventarios y la planificaci\u00f3n de la producci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a62c6f9 e-flex e-con-boxed e-con e-parent\" data-id=\"a62c6f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd2e9f1 elementor-widget elementor-widget-heading\" data-id=\"dd2e9f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"item-master-data-implementation-practices\">Pr\u00e1cticas de implantaci\u00f3n de datos maestros de art\u00edculos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2613ee e-flex e-con-boxed e-con e-parent\" data-id=\"a2613ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9146777 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"9146777\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"152332151\" aria-label=\"Pesta\u00f1as. Abre elementos con Intro o Espacio, ci\u00e9rralos con Escape y navega con las fechas.\" data-no-translation-aria-label=\"\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1523321511\" data-tab-title-id=\"e-n-tab-title-1523321511\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1523321511\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tArmonizaci\u00f3n de datos:\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1523321512\" data-tab-title-id=\"e-n-tab-title-1523321512\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1523321512\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tGobernanza de datos:\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1523321513\" data-tab-title-id=\"e-n-tab-title-1523321513\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1523321513\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tBuenas pr\u00e1cticas\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1523321511\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1523321511\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-ad1239b e-con-full e-flex e-con e-child\" data-id=\"ad1239b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a502b03 elementor-widget elementor-widget-text-editor\" data-id=\"a502b03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p>Enriquecimiento de datos mediante categorizaci\u00f3n estructurada y asignaci\u00f3n de atributos.<\/p><\/li><li><p>Establecimiento de jerarqu\u00edas de art\u00edculos y seguimiento de revisiones mediante la gesti\u00f3n de cambios de ingenier\u00eda (ECM).<\/p><\/li><li><p>Implantar estructuras multiorganizativas a nivel directivo y organizativo.<\/p><\/li><li><p>Definir atributos de referencias cruzadas para proveedores, clientes y fabricantes.<\/p><\/li><li><p>Realice auditor\u00edas para identificar duplicados, campos omitidos y anomal\u00edas.<\/p><\/li><li><p>Mantener la informaci\u00f3n de entrada, los detalles de los productos, los registros financieros y los formularios para la entrada de datos.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1523321512\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1523321512\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\"elementor-element elementor-element-1d57624 e-con-full e-flex e-con e-child\" data-id=\"1d57624\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a81a20 elementor-widget elementor-widget-text-editor\" data-id=\"0a81a20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><strong>Flujo de trabajo de gobernanza:<\/strong> Establecer claramente la propiedad de los datos, las plantillas de mantenimiento y la interconectividad de los datos.<\/p><\/li><li><p><strong>Repositorio de atributos:<\/strong> Mantener un repositorio para la gesti\u00f3n estructurada de atributos.<\/p><\/li><li><p><strong>Normas de calidad de los datos:<\/strong> Implantar la deduplicaci\u00f3n, la validaci\u00f3n, la asignaci\u00f3n y las taxonom\u00edas.<\/p><\/li><li><p><strong>Integraci\u00f3n de sistemas:<\/strong> Garantizar la compatibilidad con los sistemas ERP, SCM y de adquisiciones.<\/p><\/li><li><p><strong>Supervisi\u00f3n y mantenimiento:<\/strong> Actualizaciones y auditor\u00edas continuas para mantener la integridad de los datos.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1523321513\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1523321513\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\"elementor-element elementor-element-10e5d94 e-con-full e-flex e-con e-child\" data-id=\"10e5d94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88db550 elementor-widget elementor-widget-text-editor\" data-id=\"88db550\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p>Garantizar la coherencia mediante una clasificaci\u00f3n y unos atributos normalizados.<\/p><\/li><li><p>Integre los datos maestros de art\u00edculos con los sistemas cr\u00edticos de la empresa.<\/p><\/li><li><p>Establezca pol\u00edticas de gobernanza y flujos de trabajo claros.<\/p><\/li><li><p>Realizar auditor\u00edas peri\u00f3dicas para detectar discrepancias o deficiencias.<\/p><\/li><li><p>Mantener la colaboraci\u00f3n interfuncional entre departamentos.<\/p><\/li><li><p>Implantar herramientas automatizadas de validaci\u00f3n y gesti\u00f3n de datos.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d4db2e e-flex e-con-boxed e-con e-parent\" data-id=\"4d4db2e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4b80f1 elementor-widget elementor-widget-text-editor\" data-id=\"a4b80f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mediante la implantaci\u00f3n de pr\u00e1cticas s\u00f3lidas de datos maestros de art\u00edculos, las organizaciones pueden mejorar la eficiencia, minimizar los errores y optimizar sus procesos de gesti\u00f3n de la cadena de suministro y del inventario.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dd21b9e e-flex e-con-boxed e-con e-parent\" data-id=\"dd21b9e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d86f3f elementor-widget elementor-widget-heading\" data-id=\"8d86f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\" id=\"conclusion\">Conclusi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0af1322 e-flex e-con-boxed e-con e-parent\" data-id=\"0af1322\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef8f589 elementor-widget elementor-widget-text-editor\" data-id=\"ef8f589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En resumen, el \u00e9xito de la gesti\u00f3n de datos maestros de art\u00edculos es crucial para que su organizaci\u00f3n mantenga datos correctos, coherentes y actualizados sobre todos los materiales, productos y piezas de repuesto. Una gesti\u00f3n de datos adecuada se traduce en una mayor eficacia operativa, menos errores y una toma de decisiones m\u00e1s eficaz en las diferentes funciones empresariales, como la adquisici\u00f3n, la gesti\u00f3n de inventarios y el mantenimiento.<\/p><p>Al centralizar y estructurar la informaci\u00f3n de los art\u00edculos, las empresas pueden automatizar sus procesos, mejorar la colaboraci\u00f3n interdepartamental y, en \u00faltima instancia, conseguir un flujo de trabajo m\u00e1s fluido y eficaz. Contar con pr\u00e1cticas s\u00f3lidas de datos maestros de art\u00edculos garantiza que su empresa est\u00e9 adecuadamente preparada para gestionar las complejidades de las operaciones actuales y fomenta el \u00e9xito a largo plazo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Comprensi\u00f3n de los datos maestros de art\u00edculos en Oracle y otros sistemas ERP, modelos de datos y automatizaciones en la gesti\u00f3n de datos. <\/p>","protected":false},"author":6,"featured_media":28430,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[64],"tags":[],"class_list":["post-27736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/posts\/27736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/comments?post=27736"}],"version-history":[{"count":2,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/posts\/27736\/revisions"}],"predecessor-version":[{"id":40798,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/posts\/27736\/revisions\/40798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/media\/28430"}],"wp:attachment":[{"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/media?parent=27736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/categories?post=27736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.verdantis.com\/es\/wp-json\/wp\/v2\/tags?post=27736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}